{"id":100,"count":1,"description":"","link":"https:\/\/www.pigrecoemme.com\/blog\/tag\/laboratorio-di-televisione\/","name":"laboratorio di televisione","slug":"laboratorio-di-televisione","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>laboratorio di televisione Archivi | Scuola di Cinema Pigrecoemme - Blog<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"laboratorio di televisione Archivi | Scuola di Cinema Pigrecoemme - Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pigrecoemme.com\/blog\/tag\/laboratorio-di-televisione\/\" \/>\n<meta property=\"og:site_name\" content=\"Scuola di Cinema Pigrecoemme - Blog\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2014\/11\/pigrecoemme-test1.jpg?fit=484%2C252&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"484\" \/>\n\t<meta property=\"og:image:height\" content=\"252\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Pigrecoemme\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/tag\\\/laboratorio-di-televisione\\\/\",\"url\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/tag\\\/laboratorio-di-televisione\\\/\",\"name\":\"laboratorio di televisione Archivi | Scuola di Cinema Pigrecoemme - Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/tag\\\/laboratorio-di-televisione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/tag\\\/laboratorio-di-televisione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"laboratorio di televisione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/\",\"name\":\"Scuola di Cinema Pigrecoemme - Blog\",\"description\":\"Siamo la prima Scuola di Cinema e Fotografia di Napoli\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/#organization\",\"name\":\"Scuola di cinema e fotografia Pigrecoemme\",\"url\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.pigrecoemme.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/logo-pigrecoemme-2018.png?fit=500%2C500&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.pigrecoemme.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/logo-pigrecoemme-2018.png?fit=500%2C500&ssl=1\",\"width\":500,\"height\":500,\"caption\":\"Scuola di cinema e fotografia Pigrecoemme\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pigrecoemme\",\"https:\\\/\\\/x.com\\\/Pigrecoemme\",\"https:\\\/\\\/www.instagram.com\\\/pigrecoemme\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/pigrecoemme\\\/\",\"https:\\\/\\\/www.youtube.com\\\/pigrecoemme\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"laboratorio di televisione Archivi | Scuola di Cinema Pigrecoemme - Blog","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"laboratorio di televisione Archivi | Scuola di Cinema Pigrecoemme - Blog","og_url":"https:\/\/www.pigrecoemme.com\/blog\/tag\/laboratorio-di-televisione\/","og_site_name":"Scuola di Cinema Pigrecoemme - Blog","og_image":[{"width":484,"height":252,"url":"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2014\/11\/pigrecoemme-test1.jpg?fit=484%2C252&ssl=1","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Pigrecoemme","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.pigrecoemme.com\/blog\/tag\/laboratorio-di-televisione\/","url":"https:\/\/www.pigrecoemme.com\/blog\/tag\/laboratorio-di-televisione\/","name":"laboratorio di televisione Archivi | Scuola di Cinema Pigrecoemme - Blog","isPartOf":{"@id":"https:\/\/www.pigrecoemme.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.pigrecoemme.com\/blog\/tag\/laboratorio-di-televisione\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/www.pigrecoemme.com\/blog\/tag\/laboratorio-di-televisione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.pigrecoemme.com\/blog\/"},{"@type":"ListItem","position":2,"name":"laboratorio di televisione"}]},{"@type":"WebSite","@id":"https:\/\/www.pigrecoemme.com\/blog\/#website","url":"https:\/\/www.pigrecoemme.com\/blog\/","name":"Scuola di Cinema Pigrecoemme - Blog","description":"Siamo la prima Scuola di Cinema e Fotografia di Napoli","publisher":{"@id":"https:\/\/www.pigrecoemme.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pigrecoemme.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.pigrecoemme.com\/blog\/#organization","name":"Scuola di cinema e fotografia Pigrecoemme","url":"https:\/\/www.pigrecoemme.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.pigrecoemme.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2018\/06\/logo-pigrecoemme-2018.png?fit=500%2C500&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2018\/06\/logo-pigrecoemme-2018.png?fit=500%2C500&ssl=1","width":500,"height":500,"caption":"Scuola di cinema e fotografia Pigrecoemme"},"image":{"@id":"https:\/\/www.pigrecoemme.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pigrecoemme","https:\/\/x.com\/Pigrecoemme","https:\/\/www.instagram.com\/pigrecoemme\/","https:\/\/www.linkedin.com\/company\/pigrecoemme\/","https:\/\/www.youtube.com\/pigrecoemme"]}]}},"_links":{"self":[{"href":"https:\/\/www.pigrecoemme.com\/blog\/wp-json\/wp\/v2\/tags\/100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pigrecoemme.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.pigrecoemme.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.pigrecoemme.com\/blog\/wp-json\/wp\/v2\/posts?tags=100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}