{"id":845,"date":"2014-07-29T11:05:33","date_gmt":"2014-07-29T09:05:33","guid":{"rendered":"http:\/\/www.pigrecoemme.com\/blog\/?p=845"},"modified":"2023-12-02T19:28:11","modified_gmt":"2023-12-02T18:28:11","slug":"guarda-il-corto-commenta-e-vinci-un-corso-alla-pigrecoemme","status":"publish","type":"post","link":"https:\/\/www.pigrecoemme.com\/blog\/guarda-il-corto-commenta-e-vinci-un-corso-alla-pigrecoemme\/","title":{"rendered":"Guarda il corto, commenta e vinci un corso alla Pigrecoemme!"},"content":{"rendered":"\n<figure class=\"wp-block-image alignfull size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"484\" height=\"252\" src=\"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2014\/07\/concorso-vinci-corso.jpg?resize=484%2C252&#038;ssl=1\" alt=\"\" class=\"wp-image-846\" srcset=\"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2014\/07\/concorso-vinci-corso.jpg?w=484&amp;ssl=1 484w, https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2014\/07\/concorso-vinci-corso.jpg?resize=300%2C156&amp;ssl=1 300w\" sizes=\"auto, (max-width: 484px) 100vw, 484px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">L&#8217;amore \u00e8 un segno \u00e8 un corto diretto dal nostro docente di regia Rosario Gallone e realizzato insieme agli studenti dell&#8217;anno di corsi 2013\/2014.<\/p>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">Abbiamo deciso di pubblicarlo online e di abbinarvi un <strong>concorso<\/strong>, mettendo in palio un corso di cinema alla Pigrecoemme.<\/p>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">Dopo il corto troverete il regolamento.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"L&#039;amore \u00e8 un segno | Cortometraggio\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/nlZxrktR7As?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">&nbsp;<\/p>\n\n\n\n<h2 id=\"concorso\" class=\"wp-block-heading\">CONCORSO<\/h2>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">Guarda il cortometraggio della Pigrecoemme \u201cL&#8217;amore \u00e8 un segno\u201d, clicca mi piace e racconta nei commenti, in modo originale, il tuo amore per il cinema.<br \/>Il racconto pi\u00f9 suggestivo far\u00e0 vincere al proprio estensore un corso della scuola di cinema Pigrecoemme, a scelta tra sceneggiatura, montaggio, regia e analisi e critica.<\/p>\n\n\n\n<h2 id=\"regolamento\" class=\"wp-block-heading\">REGOLAMENTO<\/h2>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\"><em>Modalit\u00e0 di partecipazione<br \/><\/em><br \/>Per partecipare al concorso \u00e8 sufficiente e obbligatorio effettuare due operazioni:<br \/>1) Cliccare su &#8220;mi piace&#8221; sotto il video pubblicato all&#8217;url: <a href=\"https:\/\/www.facebook.com\/photo.php?v=825407294144607\">https:\/\/www.facebook.com\/photo.php?v=825407294144607<\/a><br \/>2) Scrivere, nella sezione commenti al video all&#8217;url <a href=\"https:\/\/www.facebook.com\/photo.php?v=825407294144607\">https:\/\/www.facebook.com\/photo.php?v=825407294144607<\/a> un testo di minimo 300 e massimo 1000 battute (spazi inclusi) in cui il partecipante dovr\u00e0 raccontare il suo amore per il cinema.<br \/>&#8211; Sono ammessi a partecipare gli iscritti a Facebook che siano maggiorenni alla data del 28\/07\/2014.<br \/>&#8211; Sono ammessi solo coloro che siano iscritti a Facebook con il proprio vero nome. Non sono ammessi pseudonimi e nicknames.<br \/>&#8211; Il concorso parte il 28 Luglio 2014 e scade il 15 ottobre 2014.<br \/>&#8211; Il vincitore sar\u00e0 scelto a insindacabile giudizio della giuria, composta dai fondatori della Scuola di cinema Pigrecoemme (Giacomo Fabbrocino, Rosario Gallone e Corrado Morra).<br \/>La giuria terr\u00e0 conto della forma, del contenuto e dell\u2019originalit\u00e0 del testo.<\/p>\n\n\n\n<h2 id=\"premi\" class=\"wp-block-heading\">PREMI<\/h2>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">Il premio consister\u00e0 in un corso a scelta tra quelli di regia, montaggio, sceneggiatura e analisi e critica del film, organizzati dalla scuola di cinema Pigrecoemme durante l\u2019anno accademico 2014\/2015.<br \/>I programmi di tali corsi sono consultabili a questi link:<br \/>Corso di regia: <a href=\"http:\/\/www.pigrecoemme.com\/corsi\/corso-regia.htm\">http:\/\/www.pigrecoemme.com\/corsi\/corso-regia.htm<\/a><br \/>Corso di montaggio: <a href=\"http:\/\/www.pigrecoemme.com\/corsi\/corso-montaggio-premiere.htm\">http:\/\/www.pigrecoemme.com\/corsi\/corso-montaggio-premiere.htm<\/a><br \/>Corso di sceneggiatura: <a href=\"http:\/\/www.pigrecoemme.com\/corsi\/corso-sceneggiatura.htm\">http:\/\/www.pigrecoemme.com\/corsi\/corso-sceneggiatura.htm<\/a><br \/>Corso di analisi e critica del film: <a href=\"http:\/\/www.pigrecoemme.com\/corsi\/corso-critica-cinematografica.htm\">http:\/\/www.pigrecoemme.com\/corsi\/corso-critica-cinematografica.htm<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il premio non potr\u00e0 essere commutato in denaro, n\u00e9 essere ceduto a terzi ed il vincitore potr\u00e0 usufruirne durante l\u2019anno accademico 2014\/2015.<\/p>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">Pigrecoemme comunicher\u00e0 la vittoria al partecipante selezionato solo ed esclusivamente tramite messaggio privato su Facebook.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; L&#8217;amore \u00e8 un segno \u00e8 un corto diretto dal nostro docente di regia Rosario Gallone e realizzato insieme agli studenti dell&#8217;anno di corsi 2013\/2014. Abbiamo deciso di pubblicarlo online e di abbinarvi un concorso, mettendo in palio un corso di cinema alla Pigrecoemme. Dopo il corto troverete il regolamento. &nbsp; CONCORSO Guarda il cortometraggio &#8230; <a title=\"Guarda il corto, commenta e vinci un corso alla Pigrecoemme!\" class=\"read-more\" href=\"https:\/\/www.pigrecoemme.com\/blog\/guarda-il-corto-commenta-e-vinci-un-corso-alla-pigrecoemme\/\" aria-label=\"Per saperne di pi\u00f9 su Guarda il corto, commenta e vinci un corso alla Pigrecoemme!\">Leggi tutto<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1,12,3],"tags":[130,1282,53],"class_list":["post-845","post","type-post","status-publish","format-standard","hentry","category-generale","category-produzioni","category-scuola-di-cinema","tag-cortometraggio","tag-produzioni","tag-rosario-gallone"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"L&#039;amore \u00e8 un segno \u00e8 un corto diretto dal nostro docente di regia Rosario Gallone e realizzato insieme agli studenti dell&#039;anno di corsi 2013\/2014. Abbiamo deciso di pubblicarlo online e di abbinarvi un concorso, mettendo in palio un corso di cinema alla Pigrecoemme. Dopo il corto troverete il regolamento. CONCORSO Guarda il cortometraggio\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Giacomo Fabbrocino\"\/>\n\t<meta name=\"keywords\" content=\"cortometraggio,produzioni,rosario gallone\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.pigrecoemme.com\/blog\/guarda-il-corto-commenta-e-vinci-un-corso-alla-pigrecoemme\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"it_IT\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Pigrecoemme\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Guarda il corto, commenta e vinci un corso alla Pigrecoemme!\" \/>\n\t\t<meta property=\"og:description\" content=\"L&#039;amore \u00e8 un segno \u00e8 un corto diretto dal nostro docente di regia Rosario Gallone e realizzato insieme agli studenti dell&#039;anno di corsi 2013\/2014. Abbiamo deciso di pubblicarlo online e di abbinarvi un concorso, mettendo in palio un corso di cinema alla Pigrecoemme. Dopo il corto troverete il regolamento. CONCORSO Guarda il cortometraggio\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.pigrecoemme.com\/blog\/guarda-il-corto-commenta-e-vinci-un-corso-alla-pigrecoemme\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2014\/07\/concorso-vinci-corso.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2014\/07\/concorso-vinci-corso.jpg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-07-29T09:05:33+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-12-02T18:28:11+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pigrecoemme\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@Pigrecoemme\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Guarda il corto, commenta e vinci un corso alla Pigrecoemme!\" \/>\n\t\t<meta name=\"twitter:description\" content=\"L&#039;amore \u00e8 un segno \u00e8 un corto diretto dal nostro docente di regia Rosario Gallone e realizzato insieme agli studenti dell&#039;anno di corsi 2013\/2014. Abbiamo deciso di pubblicarlo online e di abbinarvi un concorso, mettendo in palio un corso di cinema alla Pigrecoemme. Dopo il corto troverete il regolamento. CONCORSO Guarda il cortometraggio\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2014\/07\/concorso-vinci-corso.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/guarda-il-corto-commenta-e-vinci-un-corso-alla-pigrecoemme\\\/#article\",\"name\":\"Guarda il corto, commenta e vinci un corso alla Pigrecoemme!\",\"headline\":\"Guarda il corto, commenta e vinci un corso alla Pigrecoemme!\",\"author\":{\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/author\\\/giacomo-fabbrocino\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/07\\\/concorso-vinci-corso.jpg\",\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/guarda-il-corto-commenta-e-vinci-un-corso-alla-pigrecoemme\\\/#articleImage\"},\"datePublished\":\"2014-07-29T11:05:33+02:00\",\"dateModified\":\"2023-12-02T19:28:11+01:00\",\"inLanguage\":\"it-IT\",\"commentCount\":2,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/guarda-il-corto-commenta-e-vinci-un-corso-alla-pigrecoemme\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/guarda-il-corto-commenta-e-vinci-un-corso-alla-pigrecoemme\\\/#webpage\"},\"articleSection\":\"Generale, Produzioni, Scuola di cinema, cortometraggio, Produzioni, rosario gallone\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/guarda-il-corto-commenta-e-vinci-un-corso-alla-pigrecoemme\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/category\\\/generale\\\/#listItem\",\"name\":\"Generale\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/category\\\/generale\\\/#listItem\",\"position\":2,\"name\":\"Generale\",\"item\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/category\\\/generale\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/guarda-il-corto-commenta-e-vinci-un-corso-alla-pigrecoemme\\\/#listItem\",\"name\":\"Guarda il corto, commenta e vinci un corso alla Pigrecoemme!\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/guarda-il-corto-commenta-e-vinci-un-corso-alla-pigrecoemme\\\/#listItem\",\"position\":3,\"name\":\"Guarda il corto, commenta e vinci un corso alla Pigrecoemme!\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/category\\\/generale\\\/#listItem\",\"name\":\"Generale\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/#organization\",\"name\":\"Scuola di Cinema Pigrecoemme - Blog Scuola di cinema Pigrecoemme - Blog\",\"description\":\"Siamo la prima Scuola di Cinema e Fotografia di Napoli La prima scuola di cinema di Napoli. Dal 200 formiamo professionisti dell'audiovisivo.\",\"url\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/\",\"email\":\"info@pigrecoemme.com\",\"telephone\":\"+390815635188\",\"foundingDate\":\"2000-05-01\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/pigrecoemme.com\\\/img\\\/logo-pigrecoemme-2018.png\",\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/guarda-il-corto-commenta-e-vinci-un-corso-alla-pigrecoemme\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/guarda-il-corto-commenta-e-vinci-un-corso-alla-pigrecoemme\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/pigrecoemme\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@pigrecoemme\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/pigrecoemme\",\"https:\\\/\\\/linkedin.com\\\/company\\\/pigrecoemme?originalSubdomain=it\",\"https:\\\/\\\/www.threads.com\\\/@pigrecoemme\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/author\\\/giacomo-fabbrocino\\\/#author\",\"url\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/author\\\/giacomo-fabbrocino\\\/\",\"name\":\"Giacomo Fabbrocino\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/guarda-il-corto-commenta-e-vinci-un-corso-alla-pigrecoemme\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0e4dfd4d05c06a03fffaffeb36fb181415ba11b91a6b566fa2e8ada75927db32?s=96&r=g\",\"width\":96,\"height\":96,\"caption\":\"Giacomo Fabbrocino\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/guarda-il-corto-commenta-e-vinci-un-corso-alla-pigrecoemme\\\/#webpage\",\"url\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/guarda-il-corto-commenta-e-vinci-un-corso-alla-pigrecoemme\\\/\",\"name\":\"Guarda il corto, commenta e vinci un corso alla Pigrecoemme!\",\"description\":\"L'amore \\u00e8 un segno \\u00e8 un corto diretto dal nostro docente di regia Rosario Gallone e realizzato insieme agli studenti dell'anno di corsi 2013\\\/2014. Abbiamo deciso di pubblicarlo online e di abbinarvi un concorso, mettendo in palio un corso di cinema alla Pigrecoemme. Dopo il corto troverete il regolamento. CONCORSO Guarda il cortometraggio\",\"inLanguage\":\"it-IT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/guarda-il-corto-commenta-e-vinci-un-corso-alla-pigrecoemme\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/author\\\/giacomo-fabbrocino\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/author\\\/giacomo-fabbrocino\\\/#author\"},\"datePublished\":\"2014-07-29T11:05:33+02:00\",\"dateModified\":\"2023-12-02T19:28:11+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/\",\"name\":\"Scuola di Cinema Pigrecoemme - Blog\",\"alternateName\":\"NA\",\"description\":\"Siamo la prima Scuola di Cinema e Fotografia di Napoli\",\"inLanguage\":\"it-IT\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Guarda il corto, commenta e vinci un corso alla Pigrecoemme!","description":"L'amore \u00e8 un segno \u00e8 un corto diretto dal nostro docente di regia Rosario Gallone e realizzato insieme agli studenti dell'anno di corsi 2013\/2014. Abbiamo deciso di pubblicarlo online e di abbinarvi un concorso, mettendo in palio un corso di cinema alla Pigrecoemme. Dopo il corto troverete il regolamento. CONCORSO Guarda il cortometraggio","canonical_url":"https:\/\/www.pigrecoemme.com\/blog\/guarda-il-corto-commenta-e-vinci-un-corso-alla-pigrecoemme\/","robots":"max-image-preview:large","keywords":"cortometraggio,produzioni,rosario gallone","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.pigrecoemme.com\/blog\/guarda-il-corto-commenta-e-vinci-un-corso-alla-pigrecoemme\/#article","name":"Guarda il corto, commenta e vinci un corso alla Pigrecoemme!","headline":"Guarda il corto, commenta e vinci un corso alla Pigrecoemme!","author":{"@id":"https:\/\/www.pigrecoemme.com\/blog\/author\/giacomo-fabbrocino\/#author"},"publisher":{"@id":"https:\/\/www.pigrecoemme.com\/blog\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2014\/07\/concorso-vinci-corso.jpg","@id":"https:\/\/www.pigrecoemme.com\/blog\/guarda-il-corto-commenta-e-vinci-un-corso-alla-pigrecoemme\/#articleImage"},"datePublished":"2014-07-29T11:05:33+02:00","dateModified":"2023-12-02T19:28:11+01:00","inLanguage":"it-IT","commentCount":2,"mainEntityOfPage":{"@id":"https:\/\/www.pigrecoemme.com\/blog\/guarda-il-corto-commenta-e-vinci-un-corso-alla-pigrecoemme\/#webpage"},"isPartOf":{"@id":"https:\/\/www.pigrecoemme.com\/blog\/guarda-il-corto-commenta-e-vinci-un-corso-alla-pigrecoemme\/#webpage"},"articleSection":"Generale, Produzioni, Scuola di cinema, cortometraggio, Produzioni, rosario gallone"},{"@type":"BreadcrumbList","@id":"https:\/\/www.pigrecoemme.com\/blog\/guarda-il-corto-commenta-e-vinci-un-corso-alla-pigrecoemme\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.pigrecoemme.com\/blog#listItem","position":1,"name":"Home","item":"https:\/\/www.pigrecoemme.com\/blog","nextItem":{"@type":"ListItem","@id":"https:\/\/www.pigrecoemme.com\/blog\/category\/generale\/#listItem","name":"Generale"}},{"@type":"ListItem","@id":"https:\/\/www.pigrecoemme.com\/blog\/category\/generale\/#listItem","position":2,"name":"Generale","item":"https:\/\/www.pigrecoemme.com\/blog\/category\/generale\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.pigrecoemme.com\/blog\/guarda-il-corto-commenta-e-vinci-un-corso-alla-pigrecoemme\/#listItem","name":"Guarda il corto, commenta e vinci un corso alla Pigrecoemme!"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.pigrecoemme.com\/blog#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.pigrecoemme.com\/blog\/guarda-il-corto-commenta-e-vinci-un-corso-alla-pigrecoemme\/#listItem","position":3,"name":"Guarda il corto, commenta e vinci un corso alla Pigrecoemme!","previousItem":{"@type":"ListItem","@id":"https:\/\/www.pigrecoemme.com\/blog\/category\/generale\/#listItem","name":"Generale"}}]},{"@type":"Organization","@id":"https:\/\/www.pigrecoemme.com\/blog\/#organization","name":"Scuola di Cinema Pigrecoemme - Blog Scuola di cinema Pigrecoemme - Blog","description":"Siamo la prima Scuola di Cinema e Fotografia di Napoli La prima scuola di cinema di Napoli. Dal 200 formiamo professionisti dell'audiovisivo.","url":"https:\/\/www.pigrecoemme.com\/blog\/","email":"info@pigrecoemme.com","telephone":"+390815635188","foundingDate":"2000-05-01","logo":{"@type":"ImageObject","url":"https:\/\/pigrecoemme.com\/img\/logo-pigrecoemme-2018.png","@id":"https:\/\/www.pigrecoemme.com\/blog\/guarda-il-corto-commenta-e-vinci-un-corso-alla-pigrecoemme\/#organizationLogo"},"image":{"@id":"https:\/\/www.pigrecoemme.com\/blog\/guarda-il-corto-commenta-e-vinci-un-corso-alla-pigrecoemme\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/pigrecoemme\/","https:\/\/www.tiktok.com\/@pigrecoemme","https:\/\/www.youtube.com\/user\/pigrecoemme","https:\/\/linkedin.com\/company\/pigrecoemme?originalSubdomain=it","https:\/\/www.threads.com\/@pigrecoemme"]},{"@type":"Person","@id":"https:\/\/www.pigrecoemme.com\/blog\/author\/giacomo-fabbrocino\/#author","url":"https:\/\/www.pigrecoemme.com\/blog\/author\/giacomo-fabbrocino\/","name":"Giacomo Fabbrocino","image":{"@type":"ImageObject","@id":"https:\/\/www.pigrecoemme.com\/blog\/guarda-il-corto-commenta-e-vinci-un-corso-alla-pigrecoemme\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/0e4dfd4d05c06a03fffaffeb36fb181415ba11b91a6b566fa2e8ada75927db32?s=96&r=g","width":96,"height":96,"caption":"Giacomo Fabbrocino"}},{"@type":"WebPage","@id":"https:\/\/www.pigrecoemme.com\/blog\/guarda-il-corto-commenta-e-vinci-un-corso-alla-pigrecoemme\/#webpage","url":"https:\/\/www.pigrecoemme.com\/blog\/guarda-il-corto-commenta-e-vinci-un-corso-alla-pigrecoemme\/","name":"Guarda il corto, commenta e vinci un corso alla Pigrecoemme!","description":"L'amore \u00e8 un segno \u00e8 un corto diretto dal nostro docente di regia Rosario Gallone e realizzato insieme agli studenti dell'anno di corsi 2013\/2014. Abbiamo deciso di pubblicarlo online e di abbinarvi un concorso, mettendo in palio un corso di cinema alla Pigrecoemme. Dopo il corto troverete il regolamento. CONCORSO Guarda il cortometraggio","inLanguage":"it-IT","isPartOf":{"@id":"https:\/\/www.pigrecoemme.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.pigrecoemme.com\/blog\/guarda-il-corto-commenta-e-vinci-un-corso-alla-pigrecoemme\/#breadcrumblist"},"author":{"@id":"https:\/\/www.pigrecoemme.com\/blog\/author\/giacomo-fabbrocino\/#author"},"creator":{"@id":"https:\/\/www.pigrecoemme.com\/blog\/author\/giacomo-fabbrocino\/#author"},"datePublished":"2014-07-29T11:05:33+02:00","dateModified":"2023-12-02T19:28:11+01:00"},{"@type":"WebSite","@id":"https:\/\/www.pigrecoemme.com\/blog\/#website","url":"https:\/\/www.pigrecoemme.com\/blog\/","name":"Scuola di Cinema Pigrecoemme - Blog","alternateName":"NA","description":"Siamo la prima Scuola di Cinema e Fotografia di Napoli","inLanguage":"it-IT","publisher":{"@id":"https:\/\/www.pigrecoemme.com\/blog\/#organization"}}]},"og:locale":"it_IT","og:site_name":"Pigrecoemme","og:type":"article","og:title":"Guarda il corto, commenta e vinci un corso alla Pigrecoemme!","og:description":"L'amore \u00e8 un segno \u00e8 un corto diretto dal nostro docente di regia Rosario Gallone e realizzato insieme agli studenti dell'anno di corsi 2013\/2014. Abbiamo deciso di pubblicarlo online e di abbinarvi un concorso, mettendo in palio un corso di cinema alla Pigrecoemme. Dopo il corto troverete il regolamento. CONCORSO Guarda il cortometraggio","og:url":"https:\/\/www.pigrecoemme.com\/blog\/guarda-il-corto-commenta-e-vinci-un-corso-alla-pigrecoemme\/","og:image":"https:\/\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2014\/07\/concorso-vinci-corso.jpg","og:image:secure_url":"https:\/\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2014\/07\/concorso-vinci-corso.jpg","article:published_time":"2014-07-29T09:05:33+00:00","article:modified_time":"2023-12-02T18:28:11+00:00","article:publisher":"https:\/\/www.facebook.com\/pigrecoemme\/","twitter:card":"summary_large_image","twitter:site":"@Pigrecoemme","twitter:title":"Guarda il corto, commenta e vinci un corso alla Pigrecoemme!","twitter:description":"L'amore \u00e8 un segno \u00e8 un corto diretto dal nostro docente di regia Rosario Gallone e realizzato insieme agli studenti dell'anno di corsi 2013\/2014. Abbiamo deciso di pubblicarlo online e di abbinarvi un concorso, mettendo in palio un corso di cinema alla Pigrecoemme. Dopo il corto troverete il regolamento. CONCORSO Guarda il cortometraggio","twitter:image":"https:\/\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2014\/07\/concorso-vinci-corso.jpg"},"aioseo_meta_data":{"post_id":"845","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-09-30 00:38:21","updated":"2025-09-30 00:38:21","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.pigrecoemme.com\/blog\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.pigrecoemme.com\/blog\/category\/generale\/\" title=\"Generale\">Generale<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tGuarda il corto, commenta e vinci un corso alla Pigrecoemme!\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.pigrecoemme.com\/blog"},{"label":"Generale","link":"https:\/\/www.pigrecoemme.com\/blog\/category\/generale\/"},{"label":"Guarda il corto, commenta e vinci un corso alla Pigrecoemme!","link":"https:\/\/www.pigrecoemme.com\/blog\/guarda-il-corto-commenta-e-vinci-un-corso-alla-pigrecoemme\/"}],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.pigrecoemme.com\/blog\/wp-json\/wp\/v2\/posts\/845","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pigrecoemme.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pigrecoemme.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pigrecoemme.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pigrecoemme.com\/blog\/wp-json\/wp\/v2\/comments?post=845"}],"version-history":[{"count":1,"href":"https:\/\/www.pigrecoemme.com\/blog\/wp-json\/wp\/v2\/posts\/845\/revisions"}],"predecessor-version":[{"id":3483,"href":"https:\/\/www.pigrecoemme.com\/blog\/wp-json\/wp\/v2\/posts\/845\/revisions\/3483"}],"wp:attachment":[{"href":"https:\/\/www.pigrecoemme.com\/blog\/wp-json\/wp\/v2\/media?parent=845"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pigrecoemme.com\/blog\/wp-json\/wp\/v2\/categories?post=845"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pigrecoemme.com\/blog\/wp-json\/wp\/v2\/tags?post=845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}