{"id":2046,"date":"2018-02-19T18:37:18","date_gmt":"2018-02-19T17:37:18","guid":{"rendered":"http:\/\/www.pigrecoemme.com\/blog\/?p=2046"},"modified":"2018-02-20T16:52:50","modified_gmt":"2018-02-20T15:52:50","slug":"un-corso-photoshop-rapido-ed-efficace","status":"publish","type":"post","link":"https:\/\/www.pigrecoemme.com\/blog\/un-corso-photoshop-rapido-ed-efficace\/","title":{"rendered":"Cerchi un corso di Photoshop rapido ed efficace per migliorare le tue competenze fotografiche?"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2047\" src=\"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2018\/02\/corso-photoshop-napoli.jpg?resize=715%2C265&#038;ssl=1\" alt=\"\" width=\"715\" height=\"265\" srcset=\"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2018\/02\/corso-photoshop-napoli.jpg?w=715&amp;ssl=1 715w, https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2018\/02\/corso-photoshop-napoli.jpg?resize=300%2C111&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2018\/02\/corso-photoshop-napoli.jpg?resize=500%2C185&amp;ssl=1 500w\" sizes=\"auto, (max-width: 715px) 100vw, 715px\" \/><\/p>\n<p>Nel tempo il <a href=\"http:\/\/www.pigrecoemme.com\/corso-fotografia\/corso-di-fotografia-2.htm\">corso di fotografia<\/a> organizzato dalla Pigrecoemme a Napoli si \u00e8 sviluppato per offrire ai suoi allievi la possibilit\u00e0 di affrontare tutti gli aspetti della fotografia.<\/p>\n<p>Uno dei punti salienti del corso \u00e8 il Modulo D, dedicato all&#8217;uso di Photoshop. Studiato per chi abbia gi\u00e0 possesso delle basi tecniche dello scatto e voglia cimentarsi nella post-produzione: un passaggio obbligatorio, oggi, nella fotografia digitale.&nbsp;<\/p>\n<h2>Il modulo, un vero e proprio corso a se stante, inizia il 28 febbraio e costa \u20ac 350,00.<\/h2>\n<h2>Il programma del corso di Photoshop<\/h2>\n<h2>Tutte le lezioni si svolgono dalle 16:00 alle 19:00<\/h2>\n<p class=\"recensione2\">1)<strong>&nbsp;IL FLUSSO DI LAVORO DEL FOTOGRAFO DIGITALE<\/strong>&nbsp;(mercoled\u00ec 28 febbraio 2018)<br \/>\nVedremo quale \u00e8 il flusso di lavoro che deve gestire il fotografo dalla ripresa alla post-produzione. Rifletteremo anche sulle potenzialit\u00e0 e limiti del digitale.<\/p>\n<p class=\"recensione2\">2)&nbsp;<strong>LO SVILUPPO DIGITALE &#8211; CAMERA RAW<\/strong>&nbsp;(luned\u00ec 5 marzo 2018)<br \/>\nImpareremo a gestire il formato Raw, che \u00e8 il formato grafico capace di restituirci tutta la potenzialit\u00e0 delle immagini che abbiamo realizzato in fase di ripresa.<\/p>\n<p class=\"recensione2\">3)&nbsp;<strong>OTTIMIZZARE LE FOTO IN PHOTOSHOP<\/strong>&nbsp;(mercoled\u00ec 7 marzo 2018)<br \/>\nSpiegheremo come effettuare l&#8217;analisi visiva dell&#8217;immagine e decidere sugli interventi da realizzare. Panoramica delle funzioni di Photoshop. Impareremo ad ottimizzare la luminosit\u00e0, il colore e il contrasto.<\/p>\n<p class=\"recensione2\">4)&nbsp;<strong>I FILTRI&nbsp;<\/strong>(luned\u00ec 12 marzo 2018)<br \/>\nFaremo una panoramica dei filtri presenti.<br \/>\nVedremo in particolare il filtro \u201cCorrezione lente\u201d e quello \u201cLuci ed ombre\u201d.<\/p>\n<p class=\"recensione2\">5)&nbsp;<strong>I FILTRI &#8211; RITOCCARE LE FOTO. LE SELEZIONI<\/strong>&nbsp;(mercoled\u00ec 14 marzo 2018)<br \/>\nImpareremo ad intervenire sulle immagini per eliminare graffi, macchie, ed oggetti indesiderati. Effettueremo anche una panoramica sulle selezioni.&nbsp;<\/p>\n<p class=\"recensione2\">6)&nbsp;<strong>L\u2019H.D.R. E LE FOTO PANORAMICHE<\/strong>&nbsp;(luned\u00ec 19 marzo 2018)<br \/>\nImpareremo ad utilizzare le possibilit\u00e0 dell&#8217;H.D.R. che ci consente di superare i limiti della latitudine di posa del nostro supporto fotosensibile.<\/p>\n<p class=\"recensione2\">7)&nbsp;<strong>B\/N IN DIGITALE E RITOCCO VISO<\/strong>&nbsp;&nbsp;(mercoled\u00ec 21 marzo 2018)<br \/>\nSi analizzeranno le potenzialit\u00e0 e le problematiche di realizzare immagini in B|N in digitale. Si imparer\u00e0 ad effettuare i viraggi, le intonazioni e a colorare un\u2019 immagine.<br \/>\nVedremo alcuni trucchi per valorizzare un viso.<\/p>\n<p class=\"recensione2\">8)&nbsp;<strong>ESERCITAZIONE PRATICA<\/strong>&nbsp;&nbsp;(luned\u00ec 26 marzo 2018)<br \/>\nVerifica di quanto appreso durante il corso mediante alcune esercitazioni.<\/p>\n<blockquote><p>Prenotazioni&nbsp;e informazioni al numero&nbsp;<strong>081 5635188<br \/>\n<\/strong>o all&#8217;indirizzo email: <strong><a href=\"mailto:corsi@pigrecoemme.com\">corsi@pigrecoemme.com<\/a>.<\/strong><\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Nel tempo il corso di fotografia organizzato dalla Pigrecoemme a Napoli si \u00e8 sviluppato per offrire ai suoi allievi la possibilit\u00e0 di affrontare tutti gli aspetti della fotografia. Uno dei punti salienti del corso&hellip;<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[21,1],"tags":[20,1138],"class_list":["post-2046","post","type-post","status-publish","format-standard","hentry","category-fotografia","category-generale","tag-corso-di-fotografia","tag-photoshop"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aggiungi Photoshop alle tue competenze fotografiche con questo corso.<\/title>\n<meta name=\"description\" content=\"8 lezioni concentrate sulla post-produzione fotografica a Napoli.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pigrecoemme.com\/blog\/un-corso-photoshop-rapido-ed-efficace\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aggiungi Photoshop alle tue competenze fotografiche con questo corso.\" \/>\n<meta property=\"og:description\" content=\"8 lezioni concentrate sulla post-produzione fotografica a Napoli.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pigrecoemme.com\/blog\/un-corso-photoshop-rapido-ed-efficace\/\" \/>\n<meta property=\"og:site_name\" content=\"Scuola di Cinema Pigrecoemme - Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pigrecoemme\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/pigrecoemme\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-19T17:37:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-02-20T15:52:50+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2018\/02\/corso-photoshop-napoli.jpg\" \/>\n<meta name=\"author\" content=\"Pigrecoemme\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Pigrecoemme\" \/>\n<meta name=\"twitter:site\" content=\"@Pigrecoemme\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pigrecoemme\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/un-corso-photoshop-rapido-ed-efficace\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/un-corso-photoshop-rapido-ed-efficace\\\/\"},\"author\":{\"name\":\"Pigrecoemme\",\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/#\\\/schema\\\/person\\\/8996ab5bfa68cec611b330ae4a389d44\"},\"headline\":\"Cerchi un corso di Photoshop rapido ed efficace per migliorare le tue competenze fotografiche?\",\"datePublished\":\"2018-02-19T17:37:18+00:00\",\"dateModified\":\"2018-02-20T15:52:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/un-corso-photoshop-rapido-ed-efficace\\\/\"},\"wordCount\":383,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/un-corso-photoshop-rapido-ed-efficace\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/corso-photoshop-napoli.jpg\",\"keywords\":[\"\\\"corso di fotografia\\\"\",\"photoshop\"],\"articleSection\":[\"Fotografia\",\"Generale\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/un-corso-photoshop-rapido-ed-efficace\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/un-corso-photoshop-rapido-ed-efficace\\\/\",\"url\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/un-corso-photoshop-rapido-ed-efficace\\\/\",\"name\":\"Aggiungi Photoshop alle tue competenze fotografiche con questo corso.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/un-corso-photoshop-rapido-ed-efficace\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/un-corso-photoshop-rapido-ed-efficace\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/corso-photoshop-napoli.jpg\",\"datePublished\":\"2018-02-19T17:37:18+00:00\",\"dateModified\":\"2018-02-20T15:52:50+00:00\",\"description\":\"8 lezioni concentrate sulla post-produzione fotografica a Napoli.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/un-corso-photoshop-rapido-ed-efficace\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/un-corso-photoshop-rapido-ed-efficace\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/un-corso-photoshop-rapido-ed-efficace\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/corso-photoshop-napoli.jpg\",\"contentUrl\":\"http:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/corso-photoshop-napoli.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/un-corso-photoshop-rapido-ed-efficace\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cerchi un corso di Photoshop rapido ed efficace per migliorare le tue competenze fotografiche?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/\",\"name\":\"Scuola di Cinema Pigrecoemme - Blog\",\"description\":\"Siamo la prima Scuola di Cinema e Fotografia di Napoli\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/#organization\",\"name\":\"Scuola di cinema e fotografia Pigrecoemme\",\"url\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.pigrecoemme.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/logo-pigrecoemme-2018.png?fit=500%2C500&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.pigrecoemme.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/logo-pigrecoemme-2018.png?fit=500%2C500&ssl=1\",\"width\":500,\"height\":500,\"caption\":\"Scuola di cinema e fotografia Pigrecoemme\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pigrecoemme\",\"https:\\\/\\\/x.com\\\/Pigrecoemme\",\"https:\\\/\\\/www.instagram.com\\\/pigrecoemme\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/pigrecoemme\\\/\",\"https:\\\/\\\/www.youtube.com\\\/pigrecoemme\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/#\\\/schema\\\/person\\\/8996ab5bfa68cec611b330ae4a389d44\",\"name\":\"Pigrecoemme\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/541a562fed7df6fa49262cb93f0f1135b8432ec77a1bc64fdb808f64f2a8287d?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/541a562fed7df6fa49262cb93f0f1135b8432ec77a1bc64fdb808f64f2a8287d?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/541a562fed7df6fa49262cb93f0f1135b8432ec77a1bc64fdb808f64f2a8287d?s=96&r=g\",\"caption\":\"Pigrecoemme\"},\"description\":\"Profilo redazionale. Pigrecoemme \u00e8 la prima scuola di cinema, televisione e fotografia di Napoli.\",\"sameAs\":[\"http:\\\/\\\/www.pigrecoemme.com\\\/\",\"https:\\\/\\\/www.facebook.com\\\/pigrecoemme\"],\"url\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/author\\\/pigrecoemme\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aggiungi Photoshop alle tue competenze fotografiche con questo corso.","description":"8 lezioni concentrate sulla post-produzione fotografica a Napoli.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pigrecoemme.com\/blog\/un-corso-photoshop-rapido-ed-efficace\/","og_locale":"it_IT","og_type":"article","og_title":"Aggiungi Photoshop alle tue competenze fotografiche con questo corso.","og_description":"8 lezioni concentrate sulla post-produzione fotografica a Napoli.","og_url":"https:\/\/www.pigrecoemme.com\/blog\/un-corso-photoshop-rapido-ed-efficace\/","og_site_name":"Scuola di Cinema Pigrecoemme - Blog","article_publisher":"https:\/\/www.facebook.com\/pigrecoemme","article_author":"https:\/\/www.facebook.com\/pigrecoemme","article_published_time":"2018-02-19T17:37:18+00:00","article_modified_time":"2018-02-20T15:52:50+00:00","og_image":[{"url":"http:\/\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2018\/02\/corso-photoshop-napoli.jpg","type":"","width":"","height":""}],"author":"Pigrecoemme","twitter_card":"summary_large_image","twitter_creator":"@Pigrecoemme","twitter_site":"@Pigrecoemme","twitter_misc":{"Scritto da":"Pigrecoemme","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.pigrecoemme.com\/blog\/un-corso-photoshop-rapido-ed-efficace\/#article","isPartOf":{"@id":"https:\/\/www.pigrecoemme.com\/blog\/un-corso-photoshop-rapido-ed-efficace\/"},"author":{"name":"Pigrecoemme","@id":"https:\/\/www.pigrecoemme.com\/blog\/#\/schema\/person\/8996ab5bfa68cec611b330ae4a389d44"},"headline":"Cerchi un corso di Photoshop rapido ed efficace per migliorare le tue competenze fotografiche?","datePublished":"2018-02-19T17:37:18+00:00","dateModified":"2018-02-20T15:52:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.pigrecoemme.com\/blog\/un-corso-photoshop-rapido-ed-efficace\/"},"wordCount":383,"commentCount":0,"publisher":{"@id":"https:\/\/www.pigrecoemme.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.pigrecoemme.com\/blog\/un-corso-photoshop-rapido-ed-efficace\/#primaryimage"},"thumbnailUrl":"http:\/\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2018\/02\/corso-photoshop-napoli.jpg","keywords":["\"corso di fotografia\"","photoshop"],"articleSection":["Fotografia","Generale"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.pigrecoemme.com\/blog\/un-corso-photoshop-rapido-ed-efficace\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.pigrecoemme.com\/blog\/un-corso-photoshop-rapido-ed-efficace\/","url":"https:\/\/www.pigrecoemme.com\/blog\/un-corso-photoshop-rapido-ed-efficace\/","name":"Aggiungi Photoshop alle tue competenze fotografiche con questo corso.","isPartOf":{"@id":"https:\/\/www.pigrecoemme.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pigrecoemme.com\/blog\/un-corso-photoshop-rapido-ed-efficace\/#primaryimage"},"image":{"@id":"https:\/\/www.pigrecoemme.com\/blog\/un-corso-photoshop-rapido-ed-efficace\/#primaryimage"},"thumbnailUrl":"http:\/\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2018\/02\/corso-photoshop-napoli.jpg","datePublished":"2018-02-19T17:37:18+00:00","dateModified":"2018-02-20T15:52:50+00:00","description":"8 lezioni concentrate sulla post-produzione fotografica a Napoli.","breadcrumb":{"@id":"https:\/\/www.pigrecoemme.com\/blog\/un-corso-photoshop-rapido-ed-efficace\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pigrecoemme.com\/blog\/un-corso-photoshop-rapido-ed-efficace\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.pigrecoemme.com\/blog\/un-corso-photoshop-rapido-ed-efficace\/#primaryimage","url":"http:\/\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2018\/02\/corso-photoshop-napoli.jpg","contentUrl":"http:\/\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2018\/02\/corso-photoshop-napoli.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.pigrecoemme.com\/blog\/un-corso-photoshop-rapido-ed-efficace\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.pigrecoemme.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Cerchi un corso di Photoshop rapido ed efficace per migliorare le tue competenze fotografiche?"}]},{"@type":"WebSite","@id":"https:\/\/www.pigrecoemme.com\/blog\/#website","url":"https:\/\/www.pigrecoemme.com\/blog\/","name":"Scuola di Cinema Pigrecoemme - Blog","description":"Siamo la prima Scuola di Cinema e Fotografia di Napoli","publisher":{"@id":"https:\/\/www.pigrecoemme.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pigrecoemme.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.pigrecoemme.com\/blog\/#organization","name":"Scuola di cinema e fotografia Pigrecoemme","url":"https:\/\/www.pigrecoemme.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.pigrecoemme.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2018\/06\/logo-pigrecoemme-2018.png?fit=500%2C500&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2018\/06\/logo-pigrecoemme-2018.png?fit=500%2C500&ssl=1","width":500,"height":500,"caption":"Scuola di cinema e fotografia Pigrecoemme"},"image":{"@id":"https:\/\/www.pigrecoemme.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pigrecoemme","https:\/\/x.com\/Pigrecoemme","https:\/\/www.instagram.com\/pigrecoemme\/","https:\/\/www.linkedin.com\/company\/pigrecoemme\/","https:\/\/www.youtube.com\/pigrecoemme"]},{"@type":"Person","@id":"https:\/\/www.pigrecoemme.com\/blog\/#\/schema\/person\/8996ab5bfa68cec611b330ae4a389d44","name":"Pigrecoemme","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/541a562fed7df6fa49262cb93f0f1135b8432ec77a1bc64fdb808f64f2a8287d?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/541a562fed7df6fa49262cb93f0f1135b8432ec77a1bc64fdb808f64f2a8287d?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/541a562fed7df6fa49262cb93f0f1135b8432ec77a1bc64fdb808f64f2a8287d?s=96&r=g","caption":"Pigrecoemme"},"description":"Profilo redazionale. Pigrecoemme \u00e8 la prima scuola di cinema, televisione e fotografia di Napoli.","sameAs":["http:\/\/www.pigrecoemme.com\/","https:\/\/www.facebook.com\/pigrecoemme"],"url":"https:\/\/www.pigrecoemme.com\/blog\/author\/pigrecoemme\/"}]}},"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":1359,"url":"https:\/\/www.pigrecoemme.com\/blog\/corso-di-photoshop-ed-elaborazione-digitale-della-fotografia\/","url_meta":{"origin":2046,"position":0},"title":"Corso di Photoshop ed elaborazione digitale della fotografia.","author":"Pigrecoemme","date":"14 Maggio 2015","format":false,"excerpt":"Dal 10 giugno 2015 riparte il modulo del nostro corso di fotografia\u00a0diretto a chi desidera approfondire la conoscenza dell\u2019elaborazione digitale. Durante il corso si imparer\u00e0\u00a0come ottimizzare il colore, la luminosit\u00e0 ed il contrasto delle immagini, come restaurare una vecchia foto, come utilizzare il formato RAW, l\u2019H.D.R. e come realizzare delle\u2026","rel":"","context":"In &quot;Fotografia&quot;","block_context":{"text":"Fotografia","link":"https:\/\/www.pigrecoemme.com\/blog\/fotografia\/"},"img":{"alt_text":"corso di photoshop a napoli","src":"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2015\/05\/corso-photoshop-napoli.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":25,"url":"https:\/\/www.pigrecoemme.com\/blog\/il-corso-di-fotografia-cresce-parte-un-modulo-sul-digitale\/","url_meta":{"origin":2046,"position":1},"title":"Il corso di fotografia cresce: parte un modulo sul digitale","author":"Giacomo Fabbrocino","date":"18 Dicembre 2007","format":false,"excerpt":"Dalla prossima edizione che partir\u00e0 il 15 gennaio il corso di fotografia di Pigrecoemme, condotto da Luca Sorbo preveder\u00e0 un nuovo modulo in otto lezioni dedicato all\u2019elaborazione digitale: l'ottimizzazione del colore, della luminosit\u00e0 ed del contrasto delle immagini; come restaurare una vecchia foto; come utilizzare il formato RAW, lavorare con\u2026","rel":"","context":"In &quot;Generale&quot;","block_context":{"text":"Generale","link":"https:\/\/www.pigrecoemme.com\/blog\/generale\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1762,"url":"https:\/\/www.pigrecoemme.com\/blog\/lezione-gratuita-il-metodo-lab-e-il-workflow-del-fotografo-digitale\/","url_meta":{"origin":2046,"position":2},"title":"Lezione gratuita. La potenza del metodo LAB  ed il flusso di lavoro del fotografo digitale","author":"Pigrecoemme","date":"21 Settembre 2016","format":false,"excerpt":"Marted\u00ec 4 ottobre 2016 dalle 16:00 alle 18;30 alla Pigrecoemme, una lezione gratuita\u00a0per comprendere\u00a0qual \u00e8 il corretto flusso di lavoro quando si lavora con la fotografia digitale\u00a0e quali sono le potenzialit\u00e0 del metodo LAB, considerato il migliore per la correzione colore, per il contrasto, per la nitidezza e per ottenere\u2026","rel":"","context":"In &quot;Eventi&quot;","block_context":{"text":"Eventi","link":"https:\/\/www.pigrecoemme.com\/blog\/eventi\/"},"img":{"alt_text":"Lezione gratuita. Il metodo LAB e il workflow del fotografo digitale ","src":"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2016\/09\/lezionelmetodo-lab-photoshop-2.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2016\/09\/lezionelmetodo-lab-photoshop-2.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2016\/09\/lezionelmetodo-lab-photoshop-2.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2016\/09\/lezionelmetodo-lab-photoshop-2.jpg?resize=700%2C400 2x"},"classes":[]},{"id":4001,"url":"https:\/\/www.pigrecoemme.com\/blog\/corso-fotografia-napoli-5-ottobre-2026\/","url_meta":{"origin":2046,"position":3},"title":"Corso di fotografia a Napoli: il 5 ottobre parte il nuovo percorso Pigrecoemme","author":"Pigrecoemme","date":"12 Maggio 2026","format":false,"excerpt":"Corso di fotografia a Napoli: iscrizioni aperte alla Pigrecoemme Alla Pigrecoemme sono aperte le iscrizioni al nuovo corso di fotografia a Napoli, in partenza luned\u00ec 5 ottobre 2026. Un percorso semestrale pensato per chi vuole avvicinarsi alla fotografia in modo serio, pratico e progressivo, anche partendo da zero, con l\u2019obiettivo\u2026","rel":"","context":"In &quot;Fotografia&quot;","block_context":{"text":"Fotografia","link":"https:\/\/www.pigrecoemme.com\/blog\/fotografia\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":734,"url":"https:\/\/www.pigrecoemme.com\/blog\/corso-di-fotografia-a-napoli-gennaio-2014-aperte-le-iscrizioni\/","url_meta":{"origin":2046,"position":4},"title":"Corso di fotografia a Napoli gennaio 2014: aperte le iscrizioni","author":"Giacomo Fabbrocino","date":"6 Novembre 2013","format":false,"excerpt":"Sono ufficialmente aperte le iscrizioni al corso di fotografia digitale e analogica della Pigrecoemme di Napoli.La prima lezione si terr\u00e0 il 15 gennaio 2014 e il corso, articolato in 4 moduli, terminer\u00e0 il 9 aprile 2014.I quattro o moduli che compongono il ciclo di lezioni possono essere frequentati separatamente e\u2026","rel":"","context":"In &quot;Fotografia&quot;","block_context":{"text":"Fotografia","link":"https:\/\/www.pigrecoemme.com\/blog\/fotografia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2013\/11\/corso-fotografia.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2013\/11\/corso-fotografia.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2013\/11\/corso-fotografia.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2013\/11\/corso-fotografia.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":2768,"url":"https:\/\/www.pigrecoemme.com\/blog\/corso-di-fotografia-online-giugno-2020\/","url_meta":{"origin":2046,"position":5},"title":"Dal 4 giugno il corso di fotografia online","author":"Pigrecoemme","date":"27 Maggio 2020","format":false,"excerpt":"Alla nostra proposta didattica online, che ha gi\u00e0 visto riscuotere interesse e consensi con i corsi di critica cinematografica e montaggio con Adobe Premiere Pro, si aggiunge uno dei pezzi forti della nostra formazione tradizionale: il corso di fotografia condotto da Michele Salvezza, ripensato e rimodulato per essere svolto in\u2026","rel":"","context":"In &quot;Fotografia&quot;","block_context":{"text":"Fotografia","link":"https:\/\/www.pigrecoemme.com\/blog\/fotografia\/"},"img":{"alt_text":"corso online fotografia","src":"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2020\/05\/corso-online-fotografia.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2020\/05\/corso-online-fotografia.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2020\/05\/corso-online-fotografia.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2020\/05\/corso-online-fotografia.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2020\/05\/corso-online-fotografia.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.pigrecoemme.com\/blog\/wp-json\/wp\/v2\/posts\/2046","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pigrecoemme.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pigrecoemme.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pigrecoemme.com\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pigrecoemme.com\/blog\/wp-json\/wp\/v2\/comments?post=2046"}],"version-history":[{"count":0,"href":"https:\/\/www.pigrecoemme.com\/blog\/wp-json\/wp\/v2\/posts\/2046\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.pigrecoemme.com\/blog\/wp-json\/wp\/v2\/media?parent=2046"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pigrecoemme.com\/blog\/wp-json\/wp\/v2\/categories?post=2046"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pigrecoemme.com\/blog\/wp-json\/wp\/v2\/tags?post=2046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}