{"id":2022,"date":"2017-12-11T14:01:56","date_gmt":"2017-12-11T13:01:56","guid":{"rendered":"http:\/\/www.pigrecoemme.com\/blog\/?p=2022"},"modified":"2017-12-11T18:45:43","modified_gmt":"2017-12-11T17:45:43","slug":"10-migliori-film-del-2017-2","status":"publish","type":"post","link":"https:\/\/www.pigrecoemme.com\/blog\/10-migliori-film-del-2017-2\/","title":{"rendered":"I 10 migliori film del 2017"},"content":{"rendered":"<p><a href=\"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2017\/12\/Get_Out_film.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2024 size-full\" src=\"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2017\/12\/Get_Out_film.jpg?resize=860%2C361&#038;ssl=1\" alt=\"\" width=\"860\" height=\"361\" srcset=\"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2017\/12\/Get_Out_film.jpg?w=1223&amp;ssl=1 1223w, https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2017\/12\/Get_Out_film.jpg?resize=300%2C126&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2017\/12\/Get_Out_film.jpg?resize=768%2C323&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2017\/12\/Get_Out_film.jpg?resize=1024%2C430&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2017\/12\/Get_Out_film.jpg?resize=500%2C210&amp;ssl=1 500w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\" \/><\/a><\/p>\n<p>Anche il blog di Pigrecoemme, ormai, come altre riviste pi\u00f9 o meno quotate, ha, da diversi anni, un appuntamento fisso con la playlist di fine anno nella quale, in maniera parziale e arbitraria, ci mancherebbe altro, il nostro <strong>Rosario Gallone<\/strong> indica i 10 film migliori dell&#8217;anno solare (non della stagione). Ogni elenco, compreso questo, va preso nel modo giusto: confrontare i propri gusti con quelli dell&#8217;estensore, indicare i film mancanti o quelli che &#8220;perch\u00e9 questo e non quest&#8217;altro?&#8221;, una lista di consigli per visioni future. Si tratter\u00e0 di un gioco, ma di un gioco serio perch\u00e9 le analisi di un testo filmico rappresentano un esercizio critico\/speculativo col quale essere pi\u00f9 o meno d&#8217;accordo, ma che spinge alla riflessione ed allo &#8220;spettatorato attivo&#8221;. Se vogliamo trovare un <em>fil rouge<\/em> che unisce&nbsp; gran parte delle pellicole di questa playlist, possiamo individuarla nella rappresentazione del femminino e, senza allontanarsi tanto, del corpo estraneo (sia esso estraneo per razza, passato, scelte, et\u00e0). Buona lettura.<\/p>\n<p><!--more--><\/p>\n<p>1 &#8211;&nbsp;<strong>Logan&nbsp;<\/strong><em>di James Mangold<\/em><\/p>\n<p>Da sempre, in ogni genere affrontato (che fosse il dramma di <em>Dolly&#8217;s Restaurant<\/em> o il poliziesco di <em>Cop Land<\/em>, la romcom <em>Kate &amp; Leopold<\/em> o <em>Ragazze interrotte<\/em> passando per il sottovalutatissimo giallo <em>Identit\u00e0<\/em> che consiglierei di rivedere a chi si \u00e8 esaltato con <em>Split<\/em> di <strong>Shyamalan<\/strong>), con la sola eccezione dello strano oggetto <em>Knight &amp; Day<\/em>, <strong>James Mangold<\/strong> ha raccontato i disadattati. E chi \u00e8 pi\u00f9 disadattato di un supereroe? E tra i supereroi chi pi\u00f9 di uno degli X Men? E tra gli X Men chi pi\u00f9 di <strong>Wolverine<\/strong>? Era destino che a un certo punto <strong>Mangold<\/strong> si occupasse di <strong>Logan<\/strong> e, dopo averlo calato in una location giapponese, eccolo tornare al western (che \u00e8 il genere di elezione per i remake di film sui samurai) dopo il rifacimento di <em>Quel treno per Yuma<\/em>. Crepuscolare come <em>Shane<\/em>, citato letteralmente, pessimista come un <strong>Ralph Nelson<\/strong> o un <strong>Elliott Silverstein<\/strong> del Terzo Millennio.<\/p>\n<p><iframe loading=\"lazy\" title=\"Logan - The Wolverine | Trailer Ufficiale #1 [HD] | 20th Century Fox\" width=\"860\" height=\"484\" src=\"https:\/\/www.youtube.com\/embed\/DU3m1kqbNMw?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>2 &#8211;&nbsp;<strong>Manchester by the Sea&nbsp;<\/strong><em>di Kenneth Lonergan<\/em><\/p>\n<p>Durante la quarta lezione di Analisi e critica, a Pigrecoemme mostriamo un video di <strong>kogonada<\/strong> per <strong>Sight &amp; Sound<\/strong>, <em>What is Neorealism?<\/em>, in cui l&#8217;autore, confrontando le due versioni di <em>Stazione Termini<\/em> di <strong>Vittorio De Sica<\/strong> (quella italiana e quella americana), mostra come <strong>Selznick<\/strong> tagliasse ogni qual volta l&#8217;azione deviasse dal racconto principale mentre sono proprio queste deviazioni, queste piccole digressioni ad arricchire la versione director&#8217;s cut di <strong>De Sica<\/strong>. <strong>Kenneth Lonergan<\/strong>, in <em>Manchester by the Sea<\/em>, devia e indugia (i tratteggi dei vari inquilini da cui, nell&#8217;incipit, <strong>Lee Chandler<\/strong> va a sbrigare dei lavori), tesse la trama senza rincorrere i fatti. Riesce a stare perfettamente in equilibrio tra commedia e tragedia. Almeno fino alla scena in cui&nbsp;<strong>Lee Chandler<\/strong> e l&#8217;ex moglie si rivedono. E&nbsp;deflagra il dolore. <strong>Casey Affleck<\/strong> recita con occhi e postura (e ha meritatamente vinto <strong>l&#8217;Oscar<\/strong>&nbsp;come protagonista, cos\u00ec come meritato \u00e8 l&#8217;<strong>Oscar&nbsp;<\/strong>per la miglior sceneggiatura originale a&nbsp;<strong>Lonergan<\/strong> stesso)<strong>,<\/strong> ma <strong>Michelle Williams<\/strong> si dimostra ancora una volta una delle attrici pi\u00f9 sottovalutate di Hollywood.<\/p>\n<p><iframe loading=\"lazy\" title=\"Manchester by the Sea Official Trailer 1 (2016) - Casey Affleck Movie\" width=\"860\" height=\"484\" src=\"https:\/\/www.youtube.com\/embed\/gsVoD0pTge0?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>https:\/\/www.youtube.com\/watch?v=odJxAd4WU8Y<\/p>\n<p>3 &#8211;&nbsp;<strong>Jackie<\/strong>&nbsp;<em>di Pablo Larra\u00edn<\/em><\/p>\n<p><strong>Pablo Larra\u00edn<\/strong>, con le sue ultime due regie, ha piegato le regole del <em>biopic<\/em> alla sua poetica e al suo tema ricorrente: la rappresentazione. C&#8217;\u00e8 una scena in Neruda che chiarisce tutto: il poeta cileno, per sfuggire al poliziotto <strong>Peluchonneau<\/strong> (un pupazzo, una sua creazione, un po&#8217; un <strong>Clouseau<\/strong>), si nasconde in un negozio che ha esposte in vetrina delle foto e lui si sistema dietro ad una cornice vuota. Nascondersi dietro una fotografia significa che questa, cos\u00ec come il cinema, \u00e8 fisiologicamente incapace di rivelare la realt\u00e0. Ma attraverso il gioco, serio, della finzione, pu\u00f2 svelarci una verit\u00e0. <strong>Jackie<\/strong> parla della creazione della leggenda. \u00c8 il film pi\u00f9 vicino a<em> L&#8217;uomo che uccise Liberty Valance<\/em>&nbsp;mai visto di recente. <strong>Larra\u00edn<\/strong>&nbsp;ha idee precisissime di messa in scena, ma, mai come in questo caso, la sua idea non poteva bastare a s\u00e9 stessa perch\u00e9 senza la performance intensa di <strong>Natalie Portman<\/strong> (adoriamo <strong>Emma Stone<\/strong>, ma l&#8217;<strong>Oscar<\/strong> le \u00e8 stato scippato), <em>Jackie<\/em> non sarebbe il capolavoro che \u00e8.<\/p>\n<p><iframe loading=\"lazy\" title=\"JACKIE - Trailer Italiano Ufficiale | HD\" width=\"860\" height=\"484\" src=\"https:\/\/www.youtube.com\/embed\/98jgMxH6KgQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>4 &#8211;&nbsp;<strong>L&#8217;altro volto della speranza<\/strong>&nbsp;<em>di Aki Kaurism\u00e4ki<\/em><\/p>\n<p>Un paese non \u00e8 accogliente. Lo sono le persone. E un paese conta persone diverse. Ce ne sono di buone e di cattive. <em>L&#8217;altro volto della speranza<\/em> \u00e8 proprio l&#8217;aridit\u00e0 di una sentenza che riesce a non accorgersi, nega l&#8217;emergenza di <strong>Aleppo<\/strong> oppure quello, distorto dall&#8217;ignoranza, di uno skinhead che apostrofa <strong>Khaled<\/strong> con un &#8220;ebreuccio&#8221; che la dice lunga sul background sottoculturale di certi movimenti nazionalisti. Per fortuna <strong>Kaurism\u00e4ki<\/strong>&nbsp;ha ancora la voglia di raccontare favole a lieto fine (voglia che gli \u00e8 venuta da qualche film, da <em>Miracolo a Le Havre<\/em> in poi), riuscendo, come pochi, ad alternare la cronaca agghiacciante della testimonianza di <strong>Khaled<\/strong> alle esilaranti peripezie del ristorante La Pinta d&#8217;oro gestito con sorniona disillusione da <strong>Wilkstr\u00f6m<\/strong> e i suoi dipendenti. Per fortuna ha ancora voglia di speranza. Nonostante l&#8217;Europa faccia di tutto per mostrare l&#8217;altro volto.<\/p>\n<p><iframe loading=\"lazy\" title=\"L&amp;apos;altro volto della speranza - trailer ufficiale italiano\" width=\"860\" height=\"484\" src=\"https:\/\/www.youtube.com\/embed\/LghrSBcPTdE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>5 &#8211;&nbsp;<strong>La La Land<\/strong>&nbsp;<em>di Damien Chazelle<\/em><\/p>\n<p>&#8220;<em>Il cinema \u00e8 la vita senza le parti noiose<\/em>&#8220;. E la vita che vorremmo, che vorrebbero tutti \u00e8 un musical.&nbsp;<em>La La Land<\/em> \u00e8 il genere che si scontra con la realt\u00e0 e che \u00e8 destinato a rimanere confinato nell&#8217;ambito del&nbsp;<em>what if<\/em>&nbsp;(ed un ballo, al centro di un periodo cinematografico ipotetico, lo troviamo anche in&nbsp;<em>Mommy<\/em>, in&nbsp;<em>Sing Street<\/em> e in&nbsp;<em>13 Reasons Why<\/em>). Nel mondo del musical, nella sequenza del prefinale&nbsp;<em>La La Land<\/em> avrebbe vinto l&#8217;Oscar mentre nella realt\u00e0 gli \u00e8 stato scippato. Ma, per un attimo, per una breve sequenza consegnata alla storia, la fantasia di&nbsp;<strong>Damien Chazelle <\/strong>ha sfondato lo schermo e sul palco del&nbsp;<strong>Dolby Theatre<\/strong> un &#8220;altro giorno di sole&#8221; ha avuto la meglio sul &#8220;chiaro di luna&#8221;.<\/p>\n<p><iframe loading=\"lazy\" title=\"La La Land (2016 Movie) Official Trailer \u2013 &amp;apos;Dreamers&amp;apos;\" width=\"860\" height=\"484\" src=\"https:\/\/www.youtube.com\/embed\/0pdqf4P9MB8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>6 &#8211;&nbsp;<strong>L&#8217;intrusa<\/strong>&nbsp;<em>di Leonardo Di Costanzo<\/em><\/p>\n<p><strong>Leonardo Di Costanzo<\/strong> conosce il territorio in cui si svolge la vicenda narrata in&nbsp;<em>L&#8217;intrusa<\/em>. L\u00ec, proprio l\u00ec, da qualche anno si tiene il progetto formativo&nbsp;<strong>Filmap &#8211; Cinema del reale<\/strong> di cui \u00e8 direttore didattico e col quale ripercorre una strada gi\u00e0 battuta nelle esperienze formative e lavorative a&nbsp;<strong>Parigi<\/strong>. Dopo anni impiegati nel documentario (<em>A scuola<\/em>,&nbsp;<em>Odessa<\/em>) e l&#8217;esordio felice nel 2012 con&nbsp;<em>L&#8217;intervallo<\/em>, si conferma tra le voci pi\u00f9 interessanti del nostro cinema. Con&nbsp;<em>L&#8217;intrusa<\/em>,&nbsp;<strong>Di Costanzo<\/strong> non abdica alla principale virt\u00f9 della sua filmografia del reale: l&#8217;osservazione. Il regista non si schiera, guarda, sembra quasi non intervenire nel farsi dell&#8217;azione filmica, ha il controllo della messa in scena senza darlo a vedere. E la vita, quella di un quartiere complicato in cui la malavita ha la colpa di insinuarsi negli interstizi di una esistenza ordinaria (l&#8217;invasione del latitante nella masseria) e quella di chi, anche in un quartiere complicato, ad una vita ordinaria aspira e respinge quelli che con la malavita hanno legami. Come corpi estranei. Come intrusi. Giusto? Ingiusto?&nbsp;<strong>Di Costanzo<\/strong> espone una realt\u00e0, non una tesi. Non ha nulla da dimostrare. Mostra la tensione del vivere in certi luoghi (l&#8217;auto che si avvicina a&nbsp;<strong>Giovanna<\/strong> mentre torna sola a casa), la trasforma in suspence, ma una suspence che non ha sfogo catartico. La storia si chiude come si \u00e8 aperta. Con una festa. Con un&#8217;assenza. Ma senza una soluzione al problema.<\/p>\n<p><iframe loading=\"lazy\" title=\"L&amp;apos;INTRUSA - Trailer Ufficiale HD\" width=\"860\" height=\"484\" src=\"https:\/\/www.youtube.com\/embed\/zz2lWkCinxE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>7 &#8211;&nbsp;<strong>Lady Macbeth&nbsp;<\/strong><em>di William Oldroyd<\/em><\/p>\n<p>Da&nbsp;<em>Lady Macbeth del distretto di Mcensk <\/em>di <strong>Nikolaj Leskov<\/strong> (gi\u00e0 trasposto sul grande schermo, nel 1962, da&nbsp;<strong>Andrzej Wajda<\/strong> con&nbsp;<em>Lady Macbeth siberiana<\/em>), l&#8217;esordiente (al cinema perch\u00e9 trattasi di prestigioso regista teatrale)&nbsp;<strong>William Oldroyd<\/strong> ricava un debutto registico di rara intensit\u00e0 e rigore. Il neoregista ha presente la pittura fiamminga, ma anche il cinema di&nbsp;<strong>Dreyer<\/strong>,&nbsp;<strong>Rohmer<\/strong> e&nbsp;<strong>de Oliveira<\/strong>, e fa dell&#8217;inquadratura fissa la figura ricorrente, salvo nelle fughe della protagonista nella brughiera. <strong>Florence Pugh<\/strong> \u00e8 una presenza imprescindibile, che calamita l&#8217;attenzione di noi spettatori come quella dei personaggi, finanche nell&#8217;epilogo crudissimo.<\/p>\n<p><iframe loading=\"lazy\" title=\"LADY MACBETH - un film di William Oldroyd | Trailer Italiano\" width=\"860\" height=\"484\" src=\"https:\/\/www.youtube.com\/embed\/okdZPqofm94?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>8 &#8211;&nbsp;<strong>Madre!&nbsp;<\/strong><em>di Darren Aronofsky<\/em><\/p>\n<p>Il caos della creazione. O della Creazione. Ogni storia \u00e8 la Storia. Perch\u00e9 ogni atto creativo \u00e8 una Genesi. E ogni Creazione ha bisogno di Distruzione. Una vita per una vita. Ogni parto si porta via una parte della puerpera. <em>Madre!<\/em> \u00e8 un&nbsp;<em>home invasion<\/em> dell&#8217;era social. La tua &#8220;home&#8221; \u00e8 invasa da sconosciuti che si insinuano nella tua vita (perch\u00e9 glielo consenti), ti adorano, ti si offrono&nbsp;<em>vis \u00e0 vis<\/em> (salvo darti della troia arrogante se rifiuti). Il culto della personalit\u00e0 a portata di tutti. La condivisione come moderna forma di eucarestia. E&nbsp;il narcisismo dell&#8217;artista fa terra bruciata intorno a s\u00e9.&nbsp;<em>Madre!<\/em>&nbsp;\u00e8 un film epocale. Che vivr\u00e0 ben oltre il posizionamento nella classifica degli incassi. Perch\u00e9, a suo modo, contiene il passato, il presente ed il futuro della rappresentazione cinematografica. E poi ancora il passato.<\/p>\n<p><iframe loading=\"lazy\" title=\"Madre! | Trailer Ufficiale HD | Paramount Pictures 2017\" width=\"860\" height=\"484\" src=\"https:\/\/www.youtube.com\/embed\/HKiP8N-Lkbs?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>9 &#8211;&nbsp;<strong>Scappa &#8211; Get Out&nbsp;<\/strong><em>di Jordan Peel<\/em><\/p>\n<p><em>Get Out<\/em> \u00e8 il film che avrebbe potuto scrivere <strong>Ira Levin<\/strong>, magari intitolandolo <em>The Stepford Niggaz<\/em>. <em>Get Out<\/em> spiega, meglio di ogni polpettone politically correct (ogni riferimento a vincitori di premi Oscar \u00e8 voluto), come il razzismo sia figlio di un sostanziale senso di inferiorit\u00e0 del razzista. <em>Get Out<\/em> mette in scena un <em>minstrel show<\/em> neurologico in cui <em>black face<\/em> e <em>white brain<\/em> sono letterali. <em>Get Out<\/em> \u00e8 il film che solo la <strong>Blumhouse<\/strong> oggi avrebbe potuto produrre perch\u00e9 \u00e8 la casa di produzione forse pi\u00f9 indipendente d&#8217;America, la cui indipendenza \u00e8 data dagli incassi. <em>Get Out<\/em> e <em>The Purge<\/em>, non a caso, sono, infatti, i thriller pi\u00f9 politici realizzati in America negli ultimi anni.<\/p>\n<p><iframe loading=\"lazy\" title=\"SCAPPA - GET OUT - Trailer italiano ufficiale\" width=\"860\" height=\"484\" src=\"https:\/\/www.youtube.com\/embed\/6A-9yr8j2iE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>10 &#8211;&nbsp;<strong>The Handmaiden<\/strong><em> di Park Chan-wook<\/em><\/p>\n<p><strong>Park Chan-wook<\/strong>, dopo il passo falso di&nbsp;<em>Stoker<\/em>, che, per\u00f2, a questo punto assume la funzione di prova generale, torna in patria e dirige un sontuoso film tratto da&nbsp;<em>Ladra<\/em> di&nbsp;<strong>Sarah Waters<\/strong>, trasferendo l&#8217;azione dalla&nbsp;<strong>Londra&nbsp;<\/strong>vittoriana alla&nbsp;<strong>Corea<\/strong> degli anni &#8217;30 del Novecento, dominata dal Giappone. La storia di una truffa ordita ai danni di una nobildonna esonda i confini del thriller per giungere nel territorio del&nbsp;<em>m\u00e9lo<\/em> erotico, consegnando alla storia del cinema (pi\u00f9 del convenzionale nuovo inizio da un altro punto di vista) almeno un paio di scene cult: quella della limatura del dente con un ditale e quella del primo amplesso tra&nbsp;<strong>Sookee<\/strong> e&nbsp;<strong>Hideko<\/strong><\/p>\n<p><iframe loading=\"lazy\" title=\"THE HANDMAIDEN by PARK Chan-wook | Official International Trailer [HD]\" width=\"860\" height=\"484\" src=\"https:\/\/www.youtube.com\/embed\/wKpZLtt4Ctg?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anche il blog di Pigrecoemme, ormai, come altre riviste pi\u00f9 o meno quotate, ha, da diversi anni, un appuntamento fisso con la playlist di fine anno nella quale, in maniera parziale e arbitraria, ci&hellip;<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[950,1,919],"tags":[1798,67,1970,1967,1966,1800,1968,1969,1971,25,1972,1965],"class_list":["post-2022","post","type-post","status-publish","format-standard","hentry","category-analisi-e-critica-2","category-generale","category-playlist","tag-1798","tag-cinema","tag-get-out","tag-handmaiden","tag-intrusa","tag-kaurismaki","tag-la-la-land","tag-lady-macbeth","tag-logan","tag-madre","tag-manchester-by-the-sea","tag-migliori-film"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>I migliori film del 2017<\/title>\n<meta name=\"description\" content=\"Il nostro Rosario Gallone indica i 10 film migliori dell&#039;anno solare (non della stagione). Quali sono i vostri preferiti?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pigrecoemme.com\/blog\/10-migliori-film-del-2017-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"I migliori film del 2017\" \/>\n<meta property=\"og:description\" content=\"Il nostro Rosario Gallone indica i 10 film migliori dell&#039;anno solare (non della stagione). Quali sono i vostri preferiti?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pigrecoemme.com\/blog\/10-migliori-film-del-2017-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Scuola di Cinema Pigrecoemme - Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pigrecoemme\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/rosario.gallone\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-11T13:01:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-12-11T17:45:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2017\/12\/Get_Out_film.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1223\" \/>\n\t<meta property=\"og:image:height\" content=\"514\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rosario Gallone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RosarioGallone\" \/>\n<meta name=\"twitter:site\" content=\"@Pigrecoemme\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rosario Gallone\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/10-migliori-film-del-2017-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/10-migliori-film-del-2017-2\\\/\"},\"author\":{\"name\":\"Rosario Gallone\",\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/#\\\/schema\\\/person\\\/3fdd423e7c221a503812a1e86daec850\"},\"headline\":\"I 10 migliori film del 2017\",\"datePublished\":\"2017-12-11T13:01:56+00:00\",\"dateModified\":\"2017-12-11T17:45:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/10-migliori-film-del-2017-2\\\/\"},\"wordCount\":1853,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/10-migliori-film-del-2017-2\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/Get_Out_film.jpg\",\"keywords\":[\"2017\",\"cinema\",\"get out\",\"handmaiden\",\"intrusa\",\"kaurismaki\",\"la la land\",\"lady macbeth\",\"logan\",\"madre\",\"manchester by the sea\",\"migliori film\"],\"articleSection\":[\"Analisi e Critica\",\"Generale\",\"Playlist\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/10-migliori-film-del-2017-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/10-migliori-film-del-2017-2\\\/\",\"url\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/10-migliori-film-del-2017-2\\\/\",\"name\":\"I migliori film del 2017\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/10-migliori-film-del-2017-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/10-migliori-film-del-2017-2\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/Get_Out_film.jpg\",\"datePublished\":\"2017-12-11T13:01:56+00:00\",\"dateModified\":\"2017-12-11T17:45:43+00:00\",\"description\":\"Il nostro Rosario Gallone indica i 10 film migliori dell'anno solare (non della stagione). Quali sono i vostri preferiti?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/10-migliori-film-del-2017-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/10-migliori-film-del-2017-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/10-migliori-film-del-2017-2\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/Get_Out_film.jpg\",\"contentUrl\":\"http:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/Get_Out_film.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/10-migliori-film-del-2017-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I 10 migliori film del 2017\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/\",\"name\":\"Scuola di Cinema Pigrecoemme - Blog\",\"description\":\"Siamo la prima Scuola di Cinema e Fotografia di Napoli\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/#organization\",\"name\":\"Scuola di cinema e fotografia Pigrecoemme\",\"url\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.pigrecoemme.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/logo-pigrecoemme-2018.png?fit=500%2C500&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.pigrecoemme.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/logo-pigrecoemme-2018.png?fit=500%2C500&ssl=1\",\"width\":500,\"height\":500,\"caption\":\"Scuola di cinema e fotografia Pigrecoemme\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pigrecoemme\",\"https:\\\/\\\/x.com\\\/Pigrecoemme\",\"https:\\\/\\\/www.instagram.com\\\/pigrecoemme\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/pigrecoemme\\\/\",\"https:\\\/\\\/www.youtube.com\\\/pigrecoemme\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/#\\\/schema\\\/person\\\/3fdd423e7c221a503812a1e86daec850\",\"name\":\"Rosario Gallone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7172808a86a713dea422a3159a5fe73d8a0718671410a281103d82dea575d3e9?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7172808a86a713dea422a3159a5fe73d8a0718671410a281103d82dea575d3e9?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7172808a86a713dea422a3159a5fe73d8a0718671410a281103d82dea575d3e9?s=96&r=g\",\"caption\":\"Rosario Gallone\"},\"description\":\"Rosario \u00e8 tra i fondatori della Pigrecoemme, dove si occupa soprattutto del corso di regia e dell'organizzazione dei corsi. E' autore della sceneggiatura di Isa 9000 (mediometraggio con Isa Danieli diretto da Angelo Serio), del montaggio di documentari e della regia di alcuni cortometraggi.\",\"sameAs\":[\"http:\\\/\\\/www.pigrecoemme.com\\\/\",\"https:\\\/\\\/www.facebook.com\\\/rosario.gallone\",\"https:\\\/\\\/x.com\\\/RosarioGallone\"],\"url\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/author\\\/rosario-gallone\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"I migliori film del 2017","description":"Il nostro Rosario Gallone indica i 10 film migliori dell'anno solare (non della stagione). Quali sono i vostri preferiti?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pigrecoemme.com\/blog\/10-migliori-film-del-2017-2\/","og_locale":"it_IT","og_type":"article","og_title":"I migliori film del 2017","og_description":"Il nostro Rosario Gallone indica i 10 film migliori dell'anno solare (non della stagione). Quali sono i vostri preferiti?","og_url":"https:\/\/www.pigrecoemme.com\/blog\/10-migliori-film-del-2017-2\/","og_site_name":"Scuola di Cinema Pigrecoemme - Blog","article_publisher":"https:\/\/www.facebook.com\/pigrecoemme","article_author":"https:\/\/www.facebook.com\/rosario.gallone","article_published_time":"2017-12-11T13:01:56+00:00","article_modified_time":"2017-12-11T17:45:43+00:00","og_image":[{"width":1223,"height":514,"url":"https:\/\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2017\/12\/Get_Out_film.jpg","type":"image\/jpeg"}],"author":"Rosario Gallone","twitter_card":"summary_large_image","twitter_creator":"@RosarioGallone","twitter_site":"@Pigrecoemme","twitter_misc":{"Scritto da":"Rosario Gallone","Tempo di lettura stimato":"9 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.pigrecoemme.com\/blog\/10-migliori-film-del-2017-2\/#article","isPartOf":{"@id":"https:\/\/www.pigrecoemme.com\/blog\/10-migliori-film-del-2017-2\/"},"author":{"name":"Rosario Gallone","@id":"https:\/\/www.pigrecoemme.com\/blog\/#\/schema\/person\/3fdd423e7c221a503812a1e86daec850"},"headline":"I 10 migliori film del 2017","datePublished":"2017-12-11T13:01:56+00:00","dateModified":"2017-12-11T17:45:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.pigrecoemme.com\/blog\/10-migliori-film-del-2017-2\/"},"wordCount":1853,"commentCount":0,"publisher":{"@id":"https:\/\/www.pigrecoemme.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.pigrecoemme.com\/blog\/10-migliori-film-del-2017-2\/#primaryimage"},"thumbnailUrl":"http:\/\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2017\/12\/Get_Out_film.jpg","keywords":["2017","cinema","get out","handmaiden","intrusa","kaurismaki","la la land","lady macbeth","logan","madre","manchester by the sea","migliori film"],"articleSection":["Analisi e Critica","Generale","Playlist"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.pigrecoemme.com\/blog\/10-migliori-film-del-2017-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.pigrecoemme.com\/blog\/10-migliori-film-del-2017-2\/","url":"https:\/\/www.pigrecoemme.com\/blog\/10-migliori-film-del-2017-2\/","name":"I migliori film del 2017","isPartOf":{"@id":"https:\/\/www.pigrecoemme.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pigrecoemme.com\/blog\/10-migliori-film-del-2017-2\/#primaryimage"},"image":{"@id":"https:\/\/www.pigrecoemme.com\/blog\/10-migliori-film-del-2017-2\/#primaryimage"},"thumbnailUrl":"http:\/\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2017\/12\/Get_Out_film.jpg","datePublished":"2017-12-11T13:01:56+00:00","dateModified":"2017-12-11T17:45:43+00:00","description":"Il nostro Rosario Gallone indica i 10 film migliori dell'anno solare (non della stagione). Quali sono i vostri preferiti?","breadcrumb":{"@id":"https:\/\/www.pigrecoemme.com\/blog\/10-migliori-film-del-2017-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pigrecoemme.com\/blog\/10-migliori-film-del-2017-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.pigrecoemme.com\/blog\/10-migliori-film-del-2017-2\/#primaryimage","url":"http:\/\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2017\/12\/Get_Out_film.jpg","contentUrl":"http:\/\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2017\/12\/Get_Out_film.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.pigrecoemme.com\/blog\/10-migliori-film-del-2017-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.pigrecoemme.com\/blog\/"},{"@type":"ListItem","position":2,"name":"I 10 migliori film del 2017"}]},{"@type":"WebSite","@id":"https:\/\/www.pigrecoemme.com\/blog\/#website","url":"https:\/\/www.pigrecoemme.com\/blog\/","name":"Scuola di Cinema Pigrecoemme - Blog","description":"Siamo la prima Scuola di Cinema e Fotografia di Napoli","publisher":{"@id":"https:\/\/www.pigrecoemme.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pigrecoemme.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.pigrecoemme.com\/blog\/#organization","name":"Scuola di cinema e fotografia Pigrecoemme","url":"https:\/\/www.pigrecoemme.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.pigrecoemme.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2018\/06\/logo-pigrecoemme-2018.png?fit=500%2C500&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2018\/06\/logo-pigrecoemme-2018.png?fit=500%2C500&ssl=1","width":500,"height":500,"caption":"Scuola di cinema e fotografia Pigrecoemme"},"image":{"@id":"https:\/\/www.pigrecoemme.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pigrecoemme","https:\/\/x.com\/Pigrecoemme","https:\/\/www.instagram.com\/pigrecoemme\/","https:\/\/www.linkedin.com\/company\/pigrecoemme\/","https:\/\/www.youtube.com\/pigrecoemme"]},{"@type":"Person","@id":"https:\/\/www.pigrecoemme.com\/blog\/#\/schema\/person\/3fdd423e7c221a503812a1e86daec850","name":"Rosario Gallone","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/7172808a86a713dea422a3159a5fe73d8a0718671410a281103d82dea575d3e9?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7172808a86a713dea422a3159a5fe73d8a0718671410a281103d82dea575d3e9?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7172808a86a713dea422a3159a5fe73d8a0718671410a281103d82dea575d3e9?s=96&r=g","caption":"Rosario Gallone"},"description":"Rosario \u00e8 tra i fondatori della Pigrecoemme, dove si occupa soprattutto del corso di regia e dell'organizzazione dei corsi. E' autore della sceneggiatura di Isa 9000 (mediometraggio con Isa Danieli diretto da Angelo Serio), del montaggio di documentari e della regia di alcuni cortometraggi.","sameAs":["http:\/\/www.pigrecoemme.com\/","https:\/\/www.facebook.com\/rosario.gallone","https:\/\/x.com\/RosarioGallone"],"url":"https:\/\/www.pigrecoemme.com\/blog\/author\/rosario-gallone\/"}]}},"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":1831,"url":"https:\/\/www.pigrecoemme.com\/blog\/10-migliori-film-del-2017\/","url_meta":{"origin":2022,"position":0},"title":"I 10 migliori film del 2017","author":"Rosario Gallone","date":"2 Gennaio 2017","format":false,"excerpt":"Le previsioni (pi\u00f9 o meno serie) di Pigrecoemme.","rel":"","context":"In &quot;Analisi e Critica&quot;","block_context":{"text":"Analisi e Critica","link":"https:\/\/www.pigrecoemme.com\/blog\/analisi-e-critica-2\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2017\/01\/film-2017.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1820,"url":"https:\/\/www.pigrecoemme.com\/blog\/10-migliori-film-del-2016\/","url_meta":{"origin":2022,"position":1},"title":"I 10 migliori film del 2016","author":"Rosario Gallone","date":"28 Dicembre 2016","format":false,"excerpt":"Il 2016 \u00e8 donna.","rel":"","context":"In &quot;Analisi e Critica&quot;","block_context":{"text":"Analisi e Critica","link":"https:\/\/www.pigrecoemme.com\/blog\/analisi-e-critica-2\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2016\/12\/migliori-2016.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2273,"url":"https:\/\/www.pigrecoemme.com\/blog\/i-10-migliori-opening-credits-cinematografici-dal-2000-ad-oggi\/","url_meta":{"origin":2022,"position":2},"title":"I 10 migliori Opening Credits cinematografici dal 2000 ad oggi","author":"Pigrecoemme","date":"7 Novembre 2018","format":false,"excerpt":"Gli allievi di Pigrecoemme imparano prima di tutto che non si abbandona la visione di un film prima che i titoli di coda siano finiti. Perch\u00e9 bisogna onorare chi ha lavorato alla sua realizzazione. Ovviamente se queste informazioni sono in testa e ci arrivano accompagnate da un bel brano musicale\u2026","rel":"","context":"In &quot;Analisi e Critica&quot;","block_context":{"text":"Analisi e Critica","link":"https:\/\/www.pigrecoemme.com\/blog\/analisi-e-critica-2\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2018\/11\/opening-credits.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2018\/11\/opening-credits.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2018\/11\/opening-credits.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2018\/11\/opening-credits.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":2308,"url":"https:\/\/www.pigrecoemme.com\/blog\/i-10-migliori-film-del-2018\/","url_meta":{"origin":2022,"position":3},"title":"I 10 migliori film del 2018","author":"Rosario Gallone","date":"17 Dicembre 2018","format":false,"excerpt":"Come ogni anno, da almeno un lustro, anche Pigrecoemme pubblica la propria playlist dei migliori film dell'anno. Al pari del\u00a0Confiteor cristiano, anche\u00a0Rosario Gallone potrebbe dire \"ho peccato in pensieri, parole, opere e omissioni\", \u00e8 scritto nelle regole di questo gioco che non pu\u00f2 prescindere dalla parzialit\u00e0 sia di giudizio sia\u2026","rel":"","context":"In &quot;Analisi e Critica&quot;","block_context":{"text":"Analisi e Critica","link":"https:\/\/www.pigrecoemme.com\/blog\/analisi-e-critica-2\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2018\/12\/migliori-film-2018.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2018\/12\/migliori-film-2018.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2018\/12\/migliori-film-2018.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2018\/12\/migliori-film-2018.jpg?resize=700%2C400 2x"},"classes":[]},{"id":1781,"url":"https:\/\/www.pigrecoemme.com\/blog\/10-film-amerete-frequentando-master-pigrecoemme\/","url_meta":{"origin":2022,"position":4},"title":"10 film che amerete frequentando il Master Pigrecoemme","author":"Rosario Gallone","date":"22 Settembre 2016","format":false,"excerpt":"Un corso che insegna una professione, ma anche ad essere spettatori esigenti.","rel":"","context":"In &quot;Analisi e Critica&quot;","block_context":{"text":"Analisi e Critica","link":"https:\/\/www.pigrecoemme.com\/blog\/analisi-e-critica-2\/"},"img":{"alt_text":"10 film che amerete","src":"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2016\/09\/10-film-master.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1165,"url":"https:\/\/www.pigrecoemme.com\/blog\/10-migliori-film-del-2014-secondo-noi\/","url_meta":{"origin":2022,"position":5},"title":"I 10 migliori film del 2014 (secondo noi)","author":"Rosario Gallone","date":"30 Dicembre 2014","format":false,"excerpt":"Il fatto che tutti, ma proprio tutti, abbiano fatto la loro lista, ci ha fatto dubitare dell\u2019esigenza che ce ne fosse un\u2019altra. Poi abbiamo pensato comunque di stilarne una. Chiaramente ci saranno titoli che avrete trovato anche nelle altre liste ed altri che non abbiamo inserito perch\u00e9 non li abbiamo\u2026","rel":"","context":"In &quot;Analisi e Critica&quot;","block_context":{"text":"Analisi e Critica","link":"https:\/\/www.pigrecoemme.com\/blog\/analisi-e-critica-2\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2023\/12\/i-migliori-fillm-del-2014-classifica.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2023\/12\/i-migliori-fillm-del-2014-classifica.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2023\/12\/i-migliori-fillm-del-2014-classifica.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2023\/12\/i-migliori-fillm-del-2014-classifica.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2023\/12\/i-migliori-fillm-del-2014-classifica.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2023\/12\/i-migliori-fillm-del-2014-classifica.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.pigrecoemme.com\/blog\/wp-json\/wp\/v2\/posts\/2022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pigrecoemme.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pigrecoemme.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pigrecoemme.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pigrecoemme.com\/blog\/wp-json\/wp\/v2\/comments?post=2022"}],"version-history":[{"count":0,"href":"https:\/\/www.pigrecoemme.com\/blog\/wp-json\/wp\/v2\/posts\/2022\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.pigrecoemme.com\/blog\/wp-json\/wp\/v2\/media?parent=2022"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pigrecoemme.com\/blog\/wp-json\/wp\/v2\/categories?post=2022"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pigrecoemme.com\/blog\/wp-json\/wp\/v2\/tags?post=2022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}