{"id":1524,"date":"2015-10-21T18:09:13","date_gmt":"2015-10-21T16:09:13","guid":{"rendered":"http:\/\/www.pigrecoemme.com\/blog\/?p=1524"},"modified":"2015-10-21T18:09:13","modified_gmt":"2015-10-21T16:09:13","slug":"grande-giove-10-film-del-1985","status":"publish","type":"post","link":"https:\/\/www.pigrecoemme.com\/blog\/grande-giove-10-film-del-1985\/","title":{"rendered":"Grande Giove! 10 film del 1985"},"content":{"rendered":"<p><a href=\"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2015\/10\/backtothefutureday.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1525\" src=\"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2015\/10\/backtothefutureday.jpg?resize=484%2C252&#038;ssl=1\" alt=\"backtothefutureday\" width=\"484\" height=\"252\" srcset=\"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2015\/10\/backtothefutureday.jpg?w=484&amp;ssl=1 484w, https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2015\/10\/backtothefutureday.jpg?resize=300%2C156&amp;ssl=1 300w\" sizes=\"auto, (max-width: 484px) 100vw, 484px\" \/><\/a><\/p>\n<p>Lo confessiamo. A volte, diciamo pure spesso, ci sembra di essere finiti nel 2015 alternativo in cui\u00a0<strong>Biff Tannen\u00a0<\/strong>fa il bello ed il cattivo tempo. Non ci piace. Saremmo nostalgici, ma non ci piace. Allora abbiamo pensato di tornare al 1985 per mettere le cose a posto (al 1985, non al 1955, per noi i guai sono cominciati l\u00ec \ud83d\ude00 ). Come? Indicandovi una lista di film che dovreste vedere o rivedere, affinch\u00e9 magari questo futuro sia un po&#8217; diverso. In meglio. Qualche film risulter\u00e0 datato 1984, qualcuno 1986. Noi ci siamo attenuti alle liste che sono sul web, anche perch\u00e9 tra produzione e distribuzione, a volte, ci pu\u00f2 essere una discras\u00eca.<\/p>\n<p><!--more--><\/p>\n<p>1 &#8211;\u00a0<strong>Ginger e Fred<\/strong>\u00a0<em>di Federico Fellini<\/em><\/p>\n<p>Perch\u00e9\u00a0<strong>Fellini<\/strong> aveva previsto tutto. Ed in pochi lo capirono (o forse a sessanta milioni di Italiani non piacque sentirsi dare del &#8220;pecoroni&#8221;), tanto che, probabilmente, \u00e8 il suo film pi\u00f9 sottovalutato, mentre, invece, si tratta del pi\u00f9 profetico. La pubblicit\u00e0, la tv di\u00a0<strong>Paolo Limiti<\/strong>, ma anche quella delle\u00a0<em>Meteore<\/em>, dei\u00a0<em>freak show<\/em> trasmigrati dalle fiere di paese alle fiere catodiche, i presentatori poco preparati ed arroganti.\u00a0\u00c8 tutto in questa pellicola. Da vedere, insieme con <em>Prova d&#8217;orchestra<\/em>,\u00a0per sfatare il mito\u00a0di un\u00a0<strong>Fellini<\/strong>\u00a0s\u00ec autore, ma ripiegato su di s\u00e9, le sue ossessioni e la sua autobiografia.<\/p>\n<p>https:\/\/www.youtube.com\/watch?v=xcWl9ipFWZg<\/p>\n<p>2 &#8211;\u00a0<strong>Cocoon<\/strong>\u00a0<em>di Ron Howard<\/em><\/p>\n<p>Perch\u00e9 agli adolescenti del\u00a0Terzo Millennio non \u00e8 stato concesso di conoscere divi del cinema classico come\u00a0<strong>Don Ameche<\/strong>,\u00a0<strong>Hume Cronyn<\/strong>,\u00a0<strong>Jessica Tandy<\/strong>,\u00a0<strong>Maureen Stapleton<\/strong> la cui energia ritrovata, in fondo, proviene dall&#8217;Universo Cinema. Perch\u00e9 \u00e8 quello che ti rende eterno. Ma bisogna perpetuarne la visione, l&#8217;eredit\u00e0.<\/p>\n<p><iframe loading=\"lazy\" title=\"Cocoon (1985) - Trailer\" width=\"860\" height=\"484\" src=\"https:\/\/www.youtube.com\/embed\/s9BSsIX2j7M?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>3 &#8211;\u00a0<strong>Breakfast Club<\/strong>\u00a0<em>di John Hughes<\/em><\/p>\n<p>C&#8217;\u00e8 ancora qualcuno che ha il coraggio di affrontare cos\u00ec di petto il tema tipico di ogni\u00a0<em>teen movie<\/em>? Chi sono io? L&#8217;eterna domanda. Ma\u00a0<strong>John Hughes<\/strong> ci d\u00e0 anche una risposta che, come tutte le risposte che riguardano la vita, \u00e8 provvisoria. I gesti, invece, restano e quel pugno alzato di <b>Judd Nelson<\/b>\u00a0sulle note dei\u00a0<strong>Simple Minds<\/strong>\u00a0resta, eccome se resta. Date un&#8217;occhiata al primo <em>Pitch Perfect<\/em> per averne la prova.<\/p>\n<p><iframe loading=\"lazy\" title=\"The Breakfast Club finale (sub ita)\" width=\"860\" height=\"484\" src=\"https:\/\/www.youtube.com\/embed\/-bXzphW86tM?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>https:\/\/www.youtube.com\/watch?v=tZeW-A-LCSk<\/p>\n<p>4 &#8211;\u00a0<strong>Cercasi Susan disperatamente<\/strong>\u00a0<em>di Susan Seidelman<\/em><\/p>\n<p>Perch\u00e9 siamo cresciuti\u00a0<em>Into the Groove<\/em> e\u00a0<strong>Susan Seidelman\u00a0<\/strong>\u00e8 stata la miglior\u00a0narratrice del femminino di quella decade ed oltre. Come e meglio di\u00a0<strong>Flaubert<\/strong>, esplicita che\u00a0<strong>Susan<\/strong> \u00e8 lei (non \u00e8 solo omonim\u00eca), dove\u00a0<strong>Susan<\/strong> sta per donna libera, emancipata, indipendente. Lo capir\u00e0 anche\u00a0<strong>Rosanna Arquette<\/strong>.<\/p>\n<p>https:\/\/www.youtube.com\/watch?v=N6gvxdh9iuA<\/p>\n<p>5 &#8211;\u00a0<strong>Brazil<\/strong>\u00a0<em>di Terry Gilliam<\/em><\/p>\n<p>Doveva chiamarsi\u00a0<em>1984 e 1\/2<\/em> e non serve spiegare che\u00a0<strong>Orwell<\/strong> e\u00a0<strong>Fellini<\/strong> ci sono tutti (e sempre) nell&#8217;immaginario di\u00a0<strong>Terry Gilliam<\/strong>.\u00a0\u00c8 il film che ha dato un senso all&#8217;aggettivo distopico (s\u00ec, d&#8217;accordo,\u00a0<em>Blade Runner<\/em> \u00e8 del 1982, ma quella \u00e8 fantascienza) anche perch\u00e9, dopo, il mondo di nessuno di quelli che lo vide \u00e8 stato pi\u00f9 lo stesso. Ed oggi servirebbe tanto la fantasia (di\u00a0<strong>Gilliam<\/strong>) al potere.<\/p>\n<p><iframe loading=\"lazy\" title=\"Brazil (1985) Official Trailer - Jonathan Pryce, Terry Gilliam Movie HD\" width=\"860\" height=\"484\" src=\"https:\/\/www.youtube.com\/embed\/ZKPFC8DA9_8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>6 &#8211;\u00a0<strong>Phenomena<\/strong>\u00a0<em>di Dario Argento<\/em><\/p>\n<p>L&#8217;ultimo film in cui\u00a0<strong>Argento<\/strong> pare ancora avere voglia di inventare visivamente un mondo (dal successivo,\u00a0<em>Opera<\/em>, questo desiderio si appanna). Di un regista\/autore &#8220;nel genere&#8221; si sente oggi la mancanza (e non tiratemi in ballo\u00a0<strong>Stefano Sollima<\/strong> perch\u00e9 autore non \u00e8) e s\u00ec, vorremmo che il\u00a0<strong>Dario Argento<\/strong>\u00a0ritornasse quello di quegli anni, oggi, nel futuro.<\/p>\n<p>https:\/\/www.youtube.com\/watch?v=Y-5qI2JyjAc<\/p>\n<p>7 &#8211;\u00a0<strong>Il giorno degli Zombi<\/strong>\u00a0<em>di George Romero<\/em><\/p>\n<p>Perch\u00e9\u00a0<em>Les revenants<\/em> (quello di\u00a0<strong>Robin Campillo<\/strong>) forse era gi\u00e0 qui in nuce, con i tentativi della scienza di scoprire come far convivere pacificamente umani e zombi. Ed anche perch\u00e9 nel proliferare di zombi televisivi (che non ci piacciono proprio tutti) e cinematografici (che non ci piacciono per niente, tipo <em>War Z<\/em> o\u00a0quelli <em>young adult<\/em> di\u00a0<em>Warm Bodies<\/em>),\u00a0<strong>Romero<\/strong> (e gi\u00e0 lo ha dimostrato, con\u00a0<em>Diary of the Dead<\/em> soprattutto) \u00e8 quello che ha ancora qualcosa da dire sull&#8217;argomento.<\/p>\n<p><iframe loading=\"lazy\" title=\"Il Giorno degli Zombi - TRAILER - George A. Romero\" width=\"860\" height=\"645\" src=\"https:\/\/www.youtube.com\/embed\/Mnu9ry5SQqs?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>8 &#8211; <strong>A 30 secondi dalla fine<\/strong>\u00a0<em>di\u00a0Andrej Kon\u010dalovskij<\/em><\/p>\n<p>Perch\u00e9 fino a quando la\u00a0<strong>Asylum<\/strong> non produrr\u00e0 un film di\u00a0<strong>Lars Von Trier<\/strong> da un soggetto di\u00a0<strong>Victor Sj\u00f6str\u00f6m<\/strong>, nei nostri cuori rester\u00e0 solo la\u00a0<strong>Cannon<\/strong> di\u00a0<strong>Golan-Globus<\/strong> che prese un soggetto di\u00a0<strong>Akira Kurosawa<\/strong>, lo affid\u00f2 al russo\u00a0<strong>Kon\u010dalovskij<\/strong> (fratello di\u00a0<strong>Nikita Michalkov<\/strong>) e ne tir\u00f2 fuori un vero e proprio capolavoro!<\/p>\n<p><iframe loading=\"lazy\" title=\"Runaway Train - Trailer - (1985) - HQ\" width=\"860\" height=\"484\" src=\"https:\/\/www.youtube.com\/embed\/3IsWL-9kRis?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>9 &#8211;\u00a0<strong>Je vous salue, Marie<\/strong>\u00a0<em>di Jean-Luc Godard<\/em><\/p>\n<p>Perch\u00e9 \u00e8, per noi, il film pi\u00f9 dolente di\u00a0<strong>Godard<\/strong>. Traspare, tra le pieghe dei 24 fotogrammi al secondo, l&#8217;amore per la protagonista\u00a0<strong>Myriem Roussel<\/strong>,\u00a0un amore che volgeva al termine e che fu protratto proprio grazie al perdurare delle riprese. Perch\u00e9 \u00e8 un film che, lucidamente, parla ai laici di spiritualit\u00e0 e lo fa in modo rispettoso (ma i soliti ciechi difensori della cristianit\u00e0 non lo capirono) ed oggi andrebbe ri-visto per comprendere come una questione di coscienza sia un fatto privato che, in nessun modo, pu\u00f2 incidere su decisione pubbliche che riguardano tutti.<\/p>\n<p>https:\/\/www.youtube.com\/watch?v=vnd4W6g_vDU<\/p>\n<p>10 &#8211;\u00a0<strong>Pap\u00e0&#8230;\u00e8 in viaggio d&#8217;affari<\/strong>\u00a0<em>di\u00a0Emir Kusturica<\/em><\/p>\n<p>Perch\u00e9 \u00e8\u00a0<strong>Kusturica<\/strong> ed insieme non \u00e8\u00a0<strong>Kusturica<\/strong>. Perch\u00e9 la politica ha sempre avuto un peso nella filmografia del regista serbo, ma quasi mai trattata con tale\u00a0senso di frustrazione e rabbia (la vendetta del protagonista <strong>Mesa<\/strong>\u00a0\u00e8 davvero terribile).\u00a0<strong>Mesa<\/strong>\u00a0\u00e8 l&#8217;emblema che da violenza non pu\u00f2 che nascere violenza, in un circolo vizioso che non lascia spazio a speranze di riappacificazione.<\/p>\n<p><iframe loading=\"lazy\" title=\"kusturica papa \u00e8 in viaggio d&amp;apos;affari Otac na sluzbenom putu\" width=\"860\" height=\"645\" src=\"https:\/\/www.youtube.com\/embed\/ZLNLoGOck0I?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lo confessiamo. A volte, diciamo pure spesso, ci sembra di essere finiti nel 2015 alternativo in cui\u00a0Biff Tannen\u00a0fa il bello ed il cattivo tempo. Non ci piace. Saremmo nostalgici, ma non ci piace. Allora&hellip;<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[950,919],"tags":[1383,1385,1389,1394,1391,1054,1390,1392,1387,1388,1386,1393,1384],"class_list":["post-1524","post","type-post","status-publish","format-standard","hentry","category-analisi-e-critica-2","category-playlist","tag-1383","tag-breakfast-club","tag-cannon","tag-cercasi-susan-disperatamente","tag-cocoon","tag-dario-argento","tag-fellini","tag-ginger-e-fred","tag-godard","tag-konchalovkji","tag-kusturica","tag-madonna","tag-phenomena"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Grande Giove! 10 film del 1985<\/title>\n<meta name=\"description\" content=\"Che vorremmo ritornassero in questo futuro.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pigrecoemme.com\/blog\/grande-giove-10-film-del-1985\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Grande Giove! 10 film del 1985\" \/>\n<meta property=\"og:description\" content=\"Che vorremmo ritornassero in questo futuro.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pigrecoemme.com\/blog\/grande-giove-10-film-del-1985\/\" \/>\n<meta property=\"og:site_name\" content=\"Scuola di Cinema Pigrecoemme - Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pigrecoemme\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/rosario.gallone\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-21T16:09:13+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2015\/10\/backtothefutureday.jpg\" \/>\n<meta name=\"author\" content=\"Rosario Gallone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RosarioGallone\" \/>\n<meta name=\"twitter:site\" content=\"@Pigrecoemme\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rosario Gallone\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/grande-giove-10-film-del-1985\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/grande-giove-10-film-del-1985\\\/\"},\"author\":{\"name\":\"Rosario Gallone\",\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/#\\\/schema\\\/person\\\/3fdd423e7c221a503812a1e86daec850\"},\"headline\":\"Grande Giove! 10 film del 1985\",\"datePublished\":\"2015-10-21T16:09:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/grande-giove-10-film-del-1985\\\/\"},\"wordCount\":954,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/grande-giove-10-film-del-1985\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/backtothefutureday.jpg\",\"keywords\":[\"1985\",\"breakfast club\",\"cannon\",\"cercasi susan disperatamente\",\"cocoon\",\"dario argento\",\"fellini\",\"ginger e fred\",\"godard\",\"konchalovkji\",\"kusturica\",\"madonna\",\"phenomena\"],\"articleSection\":[\"Analisi e Critica\",\"Playlist\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/grande-giove-10-film-del-1985\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/grande-giove-10-film-del-1985\\\/\",\"url\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/grande-giove-10-film-del-1985\\\/\",\"name\":\"Grande Giove! 10 film del 1985\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/grande-giove-10-film-del-1985\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/grande-giove-10-film-del-1985\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/backtothefutureday.jpg\",\"datePublished\":\"2015-10-21T16:09:13+00:00\",\"description\":\"Che vorremmo ritornassero in questo futuro.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/grande-giove-10-film-del-1985\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/grande-giove-10-film-del-1985\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/grande-giove-10-film-del-1985\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/backtothefutureday.jpg\",\"contentUrl\":\"http:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/backtothefutureday.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/grande-giove-10-film-del-1985\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Grande Giove! 10 film del 1985\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/\",\"name\":\"Scuola di Cinema Pigrecoemme - Blog\",\"description\":\"Siamo la prima Scuola di Cinema e Fotografia di Napoli\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/#organization\",\"name\":\"Scuola di cinema e fotografia Pigrecoemme\",\"url\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.pigrecoemme.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/logo-pigrecoemme-2018.png?fit=500%2C500&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.pigrecoemme.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/logo-pigrecoemme-2018.png?fit=500%2C500&ssl=1\",\"width\":500,\"height\":500,\"caption\":\"Scuola di cinema e fotografia Pigrecoemme\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pigrecoemme\",\"https:\\\/\\\/x.com\\\/Pigrecoemme\",\"https:\\\/\\\/www.instagram.com\\\/pigrecoemme\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/pigrecoemme\\\/\",\"https:\\\/\\\/www.youtube.com\\\/pigrecoemme\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/#\\\/schema\\\/person\\\/3fdd423e7c221a503812a1e86daec850\",\"name\":\"Rosario Gallone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7172808a86a713dea422a3159a5fe73d8a0718671410a281103d82dea575d3e9?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7172808a86a713dea422a3159a5fe73d8a0718671410a281103d82dea575d3e9?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7172808a86a713dea422a3159a5fe73d8a0718671410a281103d82dea575d3e9?s=96&r=g\",\"caption\":\"Rosario Gallone\"},\"description\":\"Rosario \u00e8 tra i fondatori della Pigrecoemme, dove si occupa soprattutto del corso di regia e dell'organizzazione dei corsi. E' autore della sceneggiatura di Isa 9000 (mediometraggio con Isa Danieli diretto da Angelo Serio), del montaggio di documentari e della regia di alcuni cortometraggi.\",\"sameAs\":[\"http:\\\/\\\/www.pigrecoemme.com\\\/\",\"https:\\\/\\\/www.facebook.com\\\/rosario.gallone\",\"https:\\\/\\\/x.com\\\/RosarioGallone\"],\"url\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/author\\\/rosario-gallone\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Grande Giove! 10 film del 1985","description":"Che vorremmo ritornassero in questo futuro.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pigrecoemme.com\/blog\/grande-giove-10-film-del-1985\/","og_locale":"it_IT","og_type":"article","og_title":"Grande Giove! 10 film del 1985","og_description":"Che vorremmo ritornassero in questo futuro.","og_url":"https:\/\/www.pigrecoemme.com\/blog\/grande-giove-10-film-del-1985\/","og_site_name":"Scuola di Cinema Pigrecoemme - Blog","article_publisher":"https:\/\/www.facebook.com\/pigrecoemme","article_author":"https:\/\/www.facebook.com\/rosario.gallone","article_published_time":"2015-10-21T16:09:13+00:00","og_image":[{"url":"http:\/\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2015\/10\/backtothefutureday.jpg","type":"","width":"","height":""}],"author":"Rosario Gallone","twitter_card":"summary_large_image","twitter_creator":"@RosarioGallone","twitter_site":"@Pigrecoemme","twitter_misc":{"Scritto da":"Rosario Gallone","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.pigrecoemme.com\/blog\/grande-giove-10-film-del-1985\/#article","isPartOf":{"@id":"https:\/\/www.pigrecoemme.com\/blog\/grande-giove-10-film-del-1985\/"},"author":{"name":"Rosario Gallone","@id":"https:\/\/www.pigrecoemme.com\/blog\/#\/schema\/person\/3fdd423e7c221a503812a1e86daec850"},"headline":"Grande Giove! 10 film del 1985","datePublished":"2015-10-21T16:09:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.pigrecoemme.com\/blog\/grande-giove-10-film-del-1985\/"},"wordCount":954,"commentCount":0,"publisher":{"@id":"https:\/\/www.pigrecoemme.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.pigrecoemme.com\/blog\/grande-giove-10-film-del-1985\/#primaryimage"},"thumbnailUrl":"http:\/\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2015\/10\/backtothefutureday.jpg","keywords":["1985","breakfast club","cannon","cercasi susan disperatamente","cocoon","dario argento","fellini","ginger e fred","godard","konchalovkji","kusturica","madonna","phenomena"],"articleSection":["Analisi e Critica","Playlist"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.pigrecoemme.com\/blog\/grande-giove-10-film-del-1985\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.pigrecoemme.com\/blog\/grande-giove-10-film-del-1985\/","url":"https:\/\/www.pigrecoemme.com\/blog\/grande-giove-10-film-del-1985\/","name":"Grande Giove! 10 film del 1985","isPartOf":{"@id":"https:\/\/www.pigrecoemme.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pigrecoemme.com\/blog\/grande-giove-10-film-del-1985\/#primaryimage"},"image":{"@id":"https:\/\/www.pigrecoemme.com\/blog\/grande-giove-10-film-del-1985\/#primaryimage"},"thumbnailUrl":"http:\/\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2015\/10\/backtothefutureday.jpg","datePublished":"2015-10-21T16:09:13+00:00","description":"Che vorremmo ritornassero in questo futuro.","breadcrumb":{"@id":"https:\/\/www.pigrecoemme.com\/blog\/grande-giove-10-film-del-1985\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pigrecoemme.com\/blog\/grande-giove-10-film-del-1985\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.pigrecoemme.com\/blog\/grande-giove-10-film-del-1985\/#primaryimage","url":"http:\/\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2015\/10\/backtothefutureday.jpg","contentUrl":"http:\/\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2015\/10\/backtothefutureday.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.pigrecoemme.com\/blog\/grande-giove-10-film-del-1985\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.pigrecoemme.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Grande Giove! 10 film del 1985"}]},{"@type":"WebSite","@id":"https:\/\/www.pigrecoemme.com\/blog\/#website","url":"https:\/\/www.pigrecoemme.com\/blog\/","name":"Scuola di Cinema Pigrecoemme - Blog","description":"Siamo la prima Scuola di Cinema e Fotografia di Napoli","publisher":{"@id":"https:\/\/www.pigrecoemme.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pigrecoemme.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.pigrecoemme.com\/blog\/#organization","name":"Scuola di cinema e fotografia Pigrecoemme","url":"https:\/\/www.pigrecoemme.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.pigrecoemme.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2018\/06\/logo-pigrecoemme-2018.png?fit=500%2C500&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2018\/06\/logo-pigrecoemme-2018.png?fit=500%2C500&ssl=1","width":500,"height":500,"caption":"Scuola di cinema e fotografia Pigrecoemme"},"image":{"@id":"https:\/\/www.pigrecoemme.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pigrecoemme","https:\/\/x.com\/Pigrecoemme","https:\/\/www.instagram.com\/pigrecoemme\/","https:\/\/www.linkedin.com\/company\/pigrecoemme\/","https:\/\/www.youtube.com\/pigrecoemme"]},{"@type":"Person","@id":"https:\/\/www.pigrecoemme.com\/blog\/#\/schema\/person\/3fdd423e7c221a503812a1e86daec850","name":"Rosario Gallone","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/7172808a86a713dea422a3159a5fe73d8a0718671410a281103d82dea575d3e9?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7172808a86a713dea422a3159a5fe73d8a0718671410a281103d82dea575d3e9?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7172808a86a713dea422a3159a5fe73d8a0718671410a281103d82dea575d3e9?s=96&r=g","caption":"Rosario Gallone"},"description":"Rosario \u00e8 tra i fondatori della Pigrecoemme, dove si occupa soprattutto del corso di regia e dell'organizzazione dei corsi. E' autore della sceneggiatura di Isa 9000 (mediometraggio con Isa Danieli diretto da Angelo Serio), del montaggio di documentari e della regia di alcuni cortometraggi.","sameAs":["http:\/\/www.pigrecoemme.com\/","https:\/\/www.facebook.com\/rosario.gallone","https:\/\/x.com\/RosarioGallone"],"url":"https:\/\/www.pigrecoemme.com\/blog\/author\/rosario-gallone\/"}]}},"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":1165,"url":"https:\/\/www.pigrecoemme.com\/blog\/10-migliori-film-del-2014-secondo-noi\/","url_meta":{"origin":1524,"position":0},"title":"I 10 migliori film del 2014 (secondo noi)","author":"Rosario Gallone","date":"30 Dicembre 2014","format":false,"excerpt":"Il fatto che tutti, ma proprio tutti, abbiano fatto la loro lista, ci ha fatto dubitare dell\u2019esigenza che ce ne fosse un\u2019altra. Poi abbiamo pensato comunque di stilarne una. Chiaramente ci saranno titoli che avrete trovato anche nelle altre liste ed altri che non abbiamo inserito perch\u00e9 non li abbiamo\u2026","rel":"","context":"In &quot;Analisi e Critica&quot;","block_context":{"text":"Analisi e Critica","link":"https:\/\/www.pigrecoemme.com\/blog\/analisi-e-critica-2\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2023\/12\/i-migliori-fillm-del-2014-classifica.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2023\/12\/i-migliori-fillm-del-2014-classifica.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2023\/12\/i-migliori-fillm-del-2014-classifica.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2023\/12\/i-migliori-fillm-del-2014-classifica.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2023\/12\/i-migliori-fillm-del-2014-classifica.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2023\/12\/i-migliori-fillm-del-2014-classifica.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":854,"url":"https:\/\/www.pigrecoemme.com\/blog\/10-film-che-puoi-fare-a-meno-di-vedere-anche-se-i-cinefili-ti-diranno-il-contrario\/","url_meta":{"origin":1524,"position":1},"title":"10 film che puoi fare a meno di vedere anche se i cinefili ti diranno il contrario","author":"Rosario Gallone","date":"16 Ottobre 2014","format":false,"excerpt":"1 -\u00a0Requiem For a Dream di\u00a0Darren Aronofsky Perch\u00e9 \u00e8 meglio Trainspotting. E lo split screen \u00e8 cos\u00ec anni '90... 2 -\u00a0L'arco di\u00a0Kim Ki-Duk Perch\u00e9 \u00e8 comico, ma involontariamente (i cinefili si affanneranno a dirvi che lo \u00e8 volutamente). 3 -\u00a0Sogni di Akira Kurosawa Nomen Omen: vi addormentereste. 4 - La\u2026","rel":"","context":"In &quot;Playlist&quot;","block_context":{"text":"Playlist","link":"https:\/\/www.pigrecoemme.com\/blog\/analisi-e-critica-2\/playlist\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2014\/10\/film-da-evitare.png?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2014\/10\/film-da-evitare.png?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2014\/10\/film-da-evitare.png?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2014\/10\/film-da-evitare.png?resize=700%2C400 2x"},"classes":[]},{"id":2375,"url":"https:\/\/www.pigrecoemme.com\/blog\/noi-di-jordan-peele\/","url_meta":{"origin":1524,"position":2},"title":"Noi &#8211; recensione del film di di Jordan Peele","author":"Rosario Gallone","date":"5 Aprile 2019","format":false,"excerpt":"Nell\u2019incipit di Tempi Moderni, diretto da Charlie Chaplin nel 1936, un famoso raccordo analogico accosta un gregge di pecore ad una folla di operai che salgono le scale della metropolitana per recarsi in fabbrica. Chaplin racconta in poco meno di dieci secondi l\u2019alienazione del lavoro operaio. Da quella stessa metropolitana,\u2026","rel":"","context":"In &quot;Analisi e Critica&quot;","block_context":{"text":"Analisi e Critica","link":"https:\/\/www.pigrecoemme.com\/blog\/analisi-e-critica-2\/"},"img":{"alt_text":"Noi di Jordan Peele","src":"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2019\/04\/USTOP2.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2019\/04\/USTOP2.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2019\/04\/USTOP2.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2019\/04\/USTOP2.jpg?resize=700%2C400 2x, https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2019\/04\/USTOP2.jpg?resize=1050%2C600 3x"},"classes":[]},{"id":3075,"url":"https:\/\/www.pigrecoemme.com\/blog\/e-stata-la-mano-di-dio-di-paolo-sorrentino-la-recensione\/","url_meta":{"origin":1524,"position":3},"title":"\u00c8 stata la mano di Dio di Paolo Sorrentino &#8211; La recensione","author":"Rosario Gallone","date":"24 Novembre 2021","format":false,"excerpt":"C'\u00e8 qualcosa di pi\u00f9 intimamente felliniano nell'ultimo film di Paolo Sorrentino, che va ben al di l\u00e0 della superficie cui ci ha abituato. La citazione forse meno esplicita \u00e8 quella finale, quando Fabietto lascia Napoli per andare a Roma in treno come Moraldo (Franco Interlenghi) faceva in I vitelloni. E\u2026","rel":"","context":"In &quot;Analisi e Critica&quot;","block_context":{"text":"Analisi e Critica","link":"https:\/\/www.pigrecoemme.com\/blog\/analisi-e-critica-2\/"},"img":{"alt_text":"e stata la mano di dio filippo scotti","src":"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2021\/11\/e-stata-la-mano-di-dio-filippo-scotti.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2021\/11\/e-stata-la-mano-di-dio-filippo-scotti.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2021\/11\/e-stata-la-mano-di-dio-filippo-scotti.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2021\/11\/e-stata-la-mano-di-dio-filippo-scotti.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":1565,"url":"https:\/\/www.pigrecoemme.com\/blog\/10-classici-imax\/","url_meta":{"origin":1524,"position":4},"title":"10 classici che vorremmo vedere in formato IMAX","author":"Rosario Gallone","date":"15 Dicembre 2015","format":false,"excerpt":"La volont\u00e0 di aumentare l'impatto visivo, il Sense of Wonder dell'esperienza dello spettatore cinematografico, \u00e8 sempre scaturita dalla necessit\u00e0 di sconfiggere (quando non di recuperare terreno sul)la concorrenza del piccolo schermo. Il\u00a0Cinemascope e\u00a0il\u00a0Vistavision\u00a0nacquero, negli anni '50, come risposta alla profonda crisi delle sale successiva al boom della TV. Ora che\u2026","rel":"","context":"In &quot;Analisi e Critica&quot;","block_context":{"text":"Analisi e Critica","link":"https:\/\/www.pigrecoemme.com\/blog\/analisi-e-critica-2\/"},"img":{"alt_text":"10 classici che vorremmo vedere in IMAX","src":"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2015\/12\/10-film-imax.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1831,"url":"https:\/\/www.pigrecoemme.com\/blog\/10-migliori-film-del-2017\/","url_meta":{"origin":1524,"position":5},"title":"I 10 migliori film del 2017","author":"Rosario Gallone","date":"2 Gennaio 2017","format":false,"excerpt":"Le previsioni (pi\u00f9 o meno serie) di Pigrecoemme.","rel":"","context":"In &quot;Analisi e Critica&quot;","block_context":{"text":"Analisi e Critica","link":"https:\/\/www.pigrecoemme.com\/blog\/analisi-e-critica-2\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2017\/01\/film-2017.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.pigrecoemme.com\/blog\/wp-json\/wp\/v2\/posts\/1524","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pigrecoemme.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pigrecoemme.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pigrecoemme.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pigrecoemme.com\/blog\/wp-json\/wp\/v2\/comments?post=1524"}],"version-history":[{"count":0,"href":"https:\/\/www.pigrecoemme.com\/blog\/wp-json\/wp\/v2\/posts\/1524\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.pigrecoemme.com\/blog\/wp-json\/wp\/v2\/media?parent=1524"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pigrecoemme.com\/blog\/wp-json\/wp\/v2\/categories?post=1524"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pigrecoemme.com\/blog\/wp-json\/wp\/v2\/tags?post=1524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}