{"id":1516,"date":"2015-11-04T23:56:09","date_gmt":"2015-11-04T22:56:09","guid":{"rendered":"http:\/\/www.pigrecoemme.com\/blog\/?p=1516"},"modified":"2015-11-04T23:56:09","modified_gmt":"2015-11-04T22:56:09","slug":"gli-altri-bond-10-cinespie-alternative-a-007","status":"publish","type":"post","link":"https:\/\/www.pigrecoemme.com\/blog\/gli-altri-bond-10-cinespie-alternative-a-007\/","title":{"rendered":"Gli altri Bond &#8211; 10 cinespie alternative a 007"},"content":{"rendered":"<p><a href=\"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2015\/10\/bond.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1517\" src=\"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2015\/10\/bond.jpg?resize=484%2C252&#038;ssl=1\" alt=\"bond\" width=\"484\" height=\"252\" srcset=\"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2015\/10\/bond.jpg?w=484&amp;ssl=1 484w, https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2015\/10\/bond.jpg?resize=300%2C156&amp;ssl=1 300w\" sizes=\"auto, (max-width: 484px) 100vw, 484px\" \/><\/a><\/p>\n<p>Quanti epigoni, quante parodie, quanta produzione\u00a0bis ha generato il personaggio creato da\u00a0<strong>Ian Fleming<\/strong>? In occasione dell&#8217;uscita del\u00a0<strong>Bond<\/strong>\u00a0<em>movie<\/em> n. 24,\u00a0<em>Spectre <\/em>(ma sta per arrivare anche\u00a0<em>Il ponte delle spie<\/em> di\u00a0<strong>Spielberg<\/strong>), questa playlist \u00e8 dedicata a loro.<\/p>\n<p><!--more--><\/p>\n<p>1 &#8211;\u00a0<strong>Harry Palmer<\/strong><\/p>\n<p>Inventato da\u00a0<strong>Len Deighton<\/strong>, ha rappresentato, negli anni &#8217;60, davvero l&#8217;anti\u00a0<strong>Bond<\/strong>, curiosamente\u00a0interpretato da un proletario (lo era anche\u00a0<strong>Sean<\/strong>\u00a0<strong>Connery<\/strong>) quale\u00a0<strong>Michael Caine<\/strong> (era figlio di uno scaricatore di porto e di una cuoca). I film che vale la pena recuperare sono i primi tre:\u00a0<em>Ipcress<\/em>,\u00a0<em>Funerale a Berlino<\/em> e soprattutto\u00a0<em>Il\u00a0cervello da un miliardo di dollari<\/em> diretto da\u00a0<strong>Ken Russell<\/strong> capace, nell&#8217;epilogo, di citare addirittura l&#8217;<em>Aleksandr Nevskij\u00a0<\/em>di\u00a0<strong>\u0116jzen\u0161tejn<\/strong> (cliccate link sotto). Dimenticabili quelli degli anni &#8217;90,\u00a0<em>All&#8217;inseguimento della Morte Rossa<\/em> e\u00a0<em>Intrigo a San Pietroburgo<\/em>. Una volta sola,\u00a0<strong>Harry Palmer<\/strong> col suo nome alternativo di\u00a0<strong>Patrick Armstrong<\/strong>, \u00e8 stato interpretato dal carneade\u00a0<strong>Michael Petrovich<\/strong> nell&#8217;irreperibile\u00a0<em>Spy Story<\/em> del 1974.<\/p>\n<p>https:\/\/youtu.be\/pefAqlgs7K4?t=1h33m<\/p>\n<p>2 &#8211;\u00a0<strong>Hubert Bonisseur de la Bath<\/strong> &#8211;\u00a0<strong>OS 117<\/strong><\/p>\n<p><strong>Os 117<\/strong> \u00e8 nato, dalla penna di\u00a0<strong>Jean Bruce<\/strong>, prima di\u00a0<strong>James Bond<\/strong> (nel 1949), ma approd\u00f2 al cinema solo dopo il successo della creatura di\u00a0<strong>Ian Fleming<\/strong>, con l&#8217;aggiunta di una S. Ne vest\u00ec i panni soprattutto\u00a0<strong>Frederick Stafford<\/strong>, ma anche il\u00a0<strong>John Gavin\u00a0<\/strong>di\u00a0<em>Psycho<\/em> (in\u00a0<em>Niente rose per OSS 117<\/em>) e\u00a0<strong>Luc Merenda<\/strong> (in\u00a0<em>OSS 117 prend des vacances<\/em>, tratto da un romanzo della vedova di<strong> Bruce<\/strong>,\u00a0<strong>Josette<\/strong>). Nel 2006 e nel 2009, i due futuri vincitori dell&#8217;<strong>Oscar<\/strong> per\u00a0<em>The Artist<\/em>,\u00a0<strong>Jean Dujardin<\/strong> e\u00a0<strong>Michel Hazanavicius<\/strong>, realizzarono due parodie, molto accurate e divertenti (specie la prima, <em>OSS 117: Le Caire nid d&#8217;espions<\/em> nel quale il protagonista si cimenta anche con una versione franco araba di\u00a0<em>Guaglione<\/em>), del genere, ma anche dell&#8217;epoca in cui esplose (<strong>OSS 117<\/strong> \u00e8 maschilista, razzista e fondamentalmente stupido).<\/p>\n<p><iframe loading=\"lazy\" title=\"OSS117 Furia a Bahia (titoli di testa)\" width=\"860\" height=\"484\" src=\"https:\/\/www.youtube.com\/embed\/U6KMCFoTN8A?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p><iframe loading=\"lazy\" title=\"OSS 117 - Bambino\" width=\"860\" height=\"484\" src=\"https:\/\/www.youtube.com\/embed\/xGKowUNYrKA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>3 &#8211;\u00a0<strong>Jason Bourne<\/strong><\/p>\n<p>La prima volta di\u00a0<strong>Jason Bourne<\/strong> \u00e8 stata in tv, col volto di\u00a0<strong>Richard Chamberlain<\/strong> nella miniserie\u00a0<em>Identit\u00e0 bruciata (<\/em>gioco di parole tra <strong>Bourne<\/strong> e <em>burn<\/em>), ma \u00e8 dal 2002, anno della prima pellicola,\u00a0<em>The Bourne Identity<\/em> di\u00a0<strong>Doug Liman<\/strong>,\u00a0che la creatura letteraria di <strong>Robert Ludlum<\/strong>\u00a0\u00e8 entrata a pieno diritto nell&#8217;immaginario spionistico mondiale. E, per chi scrive, pi\u00f9 grazie ai sequel firmati da\u00a0<strong>Paul Greengrass<\/strong> che al prototipo.\u00a0<em>The Bourne Supremacy<\/em> e\u00a0<em>The Bourne Ultimatum<\/em> sono i migliori della serie mentre l&#8217;ultimo capitolo, diretto dallo sceneggiatore dei precedenti,\u00a0<strong>Tony Gilroy<\/strong>,\u00a0<em>The Bourne Legacy<\/em> (il primo senza\u00a0<strong>Jason<\/strong>\u00a0<strong>Bourne<\/strong> e\u00a0<strong>Matt Dillon<\/strong>), \u00e8 piuttosto deludente.<\/p>\n<p><iframe loading=\"lazy\" title=\"THE BOURNE ULTIMATUM di Paul Greengrass con Matt Damon - Trailer italiano ufficiale\" width=\"860\" height=\"484\" src=\"https:\/\/www.youtube.com\/embed\/TL9FVFHEQaI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>4 &#8211;\u00a0<strong>Mata Hari<\/strong>,\u00a0<strong>Modesty Blaise<\/strong> e le altre<\/p>\n<p>Tra tante spie di sesso maschile e di origine letteraria, l&#8217;unica di un certo rilievo di sesso femminile \u00e8 realmente esistita, sebbene la sua vita sia ammantata di leggenda. L&#8217;olandese\u00a0<strong>Margaretha Geertruida Zelle<\/strong>, danzatrice e spia, \u00e8 stata impersonata al cinema, tra le altre, dalle scandinave\u00a0<strong>Asta Nielsen<\/strong> e\u00a0<strong>Greta Garbo<\/strong> e dalla francese\u00a0<strong>Jeanne Moreau<\/strong> mentre l&#8217;unica sua connazionale a vestirne i panni \u00e8 stata\u00a0<strong>Sylvia Kristel<\/strong> (nata a\u00a0<strong>Utrecht<\/strong>) in\u00a0<em>Un corpo da spiare<\/em> di\u00a0<strong>Curtis Harrington<\/strong>. In\u00a0<strong>Italia<\/strong> l&#8217;hanno impersonata\u00a0<strong>Cosetta Greco<\/strong> nello sceneggiato televisivo\u00a0<em>Dossier Mata Hari<\/em> e\u00a0<strong>Veronica Pivetti<\/strong>, alla radio, in\u00a0<em>Mata Hari: La doppia vita di Greta Zelle<\/em>. Le altre spie donna hanno avuto vita breve: sia la <strong>Modesty Blaise\/Monica Vitti<\/strong> di\u00a0<em>Modesty Blaise &#8211; La bellissima che uccide\u00a0<\/em>che\u00a0<strong>Joseph Losey<\/strong> trasse, dall&#8217;omonima striscia di\u00a0<strong>Peter O&#8217; Donnell<\/strong>, con gusto pop e molto\u00a0<em>swinging london<\/em>, sia la\u00a0<strong>Lili Smith<\/strong>\/<strong>Julie Andrews<\/strong> di\u00a0<em>Operazione Cr\u00eapes Suzette<\/em> di\u00a0<strong>Blake Edwards<\/strong>, senza tener conto dei vari\u00a0<em>Salt<strong>\u00a0<\/strong><\/em>(<strong>Angelina Jolie<\/strong>) o il pi\u00f9 vecchio\u00a0<em>Spy<\/em> (<strong>Geena Davis<\/strong>). Probabilmente la spia donna pi\u00f9 famosa dell&#8217;audiovisivo \u00e8 la\u00a0<strong>Sidney Bristow<\/strong> protagonista di\u00a0<em>Alias<\/em>, telefilm di culto creato da\u00a0<strong>J.J.Abrams<\/strong>.<\/p>\n<p><iframe loading=\"lazy\" title=\"Dossier Mata Hari (1967) 1x4\" width=\"860\" height=\"645\" src=\"https:\/\/www.youtube.com\/embed\/SQfjklLQ66I?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>5 &#8211;\u00a0<strong>George Smiley<\/strong><\/p>\n<p>Creato da\u00a0<strong>John Le Carr\u00e9<\/strong>, scrittore oltre che a sua volta agente segreto del\u00a0<strong>SIS<\/strong> (<strong>Secret Intelligence Service<\/strong>),\u00a0<strong>George Smiley<\/strong> \u00e8 stato forse la spia simbolo della &#8220;Guerra Fredda&#8221;, protagonista di un classico di quel periodo,\u00a0<em>Chiamata per il morto<\/em> di\u00a0<strong>Sidney Lumet<\/strong> (ad interpretarlo\u00a0<strong>James Mason<\/strong>), mentre in\u00a0<em>La spia che venne dal freddo<\/em><em>\u00a0<\/em>(la cui trasposizione cinematografica, anch&#8217;essa famosissima, fu diretta da\u00a0<strong>Martin Ritt<\/strong>) ha un ruolo secondario (e sul grande schermo il volto di\u00a0<strong>Rupert Davies<\/strong>). L&#8217;opera, per\u00f2, per la quale \u00e8 maggiormente noto \u00e8\u00a0<em>Tinker, Tailor, Soldier, Spy<\/em> (in italiano\u00a0<em>La talpa<\/em>) che ha avuto due adattamenti, uno televisivo ed uno cinematografico, entrambi molto riusciti ed in entrambi impersonato da due grandi attori:\u00a0<strong>Alec Guinness<\/strong> nella miniserie tv del 1979 (e nel seguito <em>Smiley&#8217;s People<\/em> del 1982)\u00a0e\u00a0<strong>Gary Oldman<\/strong> nel bel film di\u00a0<strong>Tomas Alfredson<\/strong> del 2011.<\/p>\n<p><iframe loading=\"lazy\" title=\"&quot;Vintage&quot; Tinker Tailor Soldier Spy Trailer\" width=\"860\" height=\"484\" src=\"https:\/\/www.youtube.com\/embed\/Lc2H_uPmLu4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p><iframe loading=\"lazy\" title=\"La Talpa - Trailer Ufficiale (ITA)\" width=\"860\" height=\"484\" src=\"https:\/\/www.youtube.com\/embed\/j8kUkKMiVI0?start=14&amp;feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>6 &#8211;\u00a0<strong>James Tont<\/strong><\/p>\n<p>Niente a che fare con lo stupidissimo personaggio di\u00a0<strong>Zelig<\/strong>. Tra le tante parodie spionistiche, quelle italiane (specie negli anni &#8217;60 eravamo maestri del genere) restano le migliori. Oltre ai due\u00a0<strong>Franco &amp; Ciccio\u00a0<\/strong><em>movie\u00a0<\/em>(<em>002 agenti segretissimi<\/em>,\u00a0<em>002 Operazione luna<\/em> e\u00a0<em>Come rubammo la bomba atomica<\/em> di\u00a0<strong>Lucio Fulci<\/strong>,\u00a0<em>Due mafiosi contro Goldginger<\/em> di\u00a0<strong>Giorgio Simonelli<\/strong> ed il pi\u00f9 riuscito\u00a0<em>Le spie vengono dal semifreddo<\/em> di\u00a0<strong>Mario Bava<\/strong> con\u00a0<strong>Vincent Price<\/strong> nel ruolo del\u00a0<strong>Dr.\u00a0Goldfoot<\/strong>, gi\u00e0 interpretato l&#8217;anno prima in\u00a0<em>Dr. Goldfoot and the Bikini Machine<\/em>, crossover, prodotto dall&#8217;<strong>AIP\u00a0<\/strong>di\u00a0<strong>Nicholson\/Arkoff<\/strong>, tra lo spionistico ed il\u00a0<em>beach movie<\/em>), particolarmente riuscite furono le due regie di\u00a0<strong>Bruno Corbucci<\/strong> con\u00a0<strong>Lando Buzzanca<\/strong> protagonista: lo spy-musicarello\u00a0<em>James Tont Operazione U.N.O.\u00a0<\/em>(in cui il protagonista si scontra con un cattivo chiamato\u00a0<strong>Goldsinger<\/strong>) e\u00a0<em>James Tont Operazione D.U.E.<\/em><\/p>\n<p>https:\/\/www.youtube.com\/watch?v=30yvMbTFQfE<\/p>\n<p>https:\/\/www.youtube.com\/watch?v=pVTnV-AMysQ<\/p>\n<p>7 &#8211;\u00a0<strong>Matt Helm<\/strong><\/p>\n<p>Magari lo si ricorda soprattutto protagonista di una serie tv giallo-rosa in cui a vestirne i panni \u00e8\u00a0<strong>Anthony Franciosa<\/strong>, ma la creazione letteraria di\u00a0<strong>Donald Hamilton<\/strong> (un agente segreto, quasi un sicario) ebbe quattro trasposizioni cinematografiche (ai limiti della parodia) in cui ad impersonarlo \u00e8\u00a0<strong>Dean Martin<\/strong>:\u00a0<em>Matt Helm il silenziatore<\/em>,\u00a0<em>Matt Helm&#8230;non perdona!<\/em>,\u00a0<em>L&#8217;imboscata<\/em> (inserito tra i peggiori 50 film di sempre in\u00a0<em>The Fifty Worst Films of All Time<\/em>,\u00a0libro del 1978 scritto da<strong> Harry Medved<\/strong>, <strong>Randy Dreyfuss<\/strong> e<strong> Michael Medved<\/strong>),\u00a0<em>Missione compiuta stop. Bacioni Matt Helm<\/em> in cui il\u00a0<em>villain<\/em> conte\u00a0<strong>Contini<\/strong>\u00a0\u00e8\u00a0<strong>Nigel Green<\/strong>\u00a0(che di agenti segreti se ne intendeva essendo apparso, in TV, in\u00a0<em>The Avengers<\/em>,\u00a0<em>The Persuaders<\/em> e\u00a0<em>The Protectors<\/em>), mentre tra gli avversari compare anche\u00a0<strong>Chuck Norris<\/strong> e\u00a0<strong>Bruce Lee<\/strong> fu l&#8217;insegnante di karate sul set.<\/p>\n<p><iframe loading=\"lazy\" title=\"&quot;Matt Helm&quot; TV Intro\" width=\"860\" height=\"645\" src=\"https:\/\/www.youtube.com\/embed\/ws5PvZsMDfY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>https:\/\/www.youtube.com\/watch?v=KqFLpdIzhH8<\/p>\n<p>8 &#8211;\u00a0<strong>Ethan Hunt<\/strong><\/p>\n<p>Dei tanti qui citati, fatta eccezione per le parodie, probabilmente\u00a0<strong>Ethan Hunt<\/strong> \u00e8 l&#8217;unico agente segreto nato esclusivamente per il cinema. Nella serie televisiva di culto (introdotta da un tema di <strong>Lalo Schifrin<\/strong> altrettanto, se non maggiormente, di culto)\u00a0da cui, a partire dal 1996, \u00e8 stata tratta una serie di film con protagonista\u00a0<strong>Tom Cruise<\/strong>, il personaggio di\u00a0<strong>Hunt<\/strong> non esiste. Esiste, per\u00f2, quello di\u00a0<strong>Jim Phelps<\/strong> che trasmigra dal piccolo al grande schermo col volto di\u00a0<strong>Jon Voight<\/strong> (sul piccolo \u00e8 l&#8217;indimenticabile\u00a0<strong>Peter Graves<\/strong>), ma solo nel primo film della serie (e non vi diciamo perch\u00e9). A tutt&#8217;oggi\u00a0<strong>Hunt<\/strong> \u00e8 stato protagonista di cinque pellicole, di cui la migliore resta la prima\u00a0diretta\u00a0da\u00a0<strong>Brian De Palma\u00a0<\/strong>(la seconda \u00e8 un remake poco riuscito\u00a0di\u00a0<em>Notorious<\/em> di\u00a0<strong>Hitchcock<\/strong> firmata da\u00a0<strong>John Woo<\/strong>; la terza \u00e8 l&#8217;esordio dietro una mdp cinematografica di\u00a0<strong>J.J.Abrams<\/strong> che porta in dote gli intrecci spionistico-familiari della sua serie\u00a0<em>Alias<\/em>, la quarta \u00e8 il primo film in\u00a0<em>live action<\/em> di\u00a0<strong>Brad Bird<\/strong> artefice di\u00a0<em>Gli incredibili<\/em> e\u00a0<em>Ratatouille<\/em> e la quinta un nuovo capitolo del sodalizio\u00a0<strong>Cruise<\/strong>\/<strong>McQuarrie<\/strong>, rodata in\u00a0<em>Jack Reacher<\/em>).<\/p>\n<p><iframe loading=\"lazy\" title=\"Mission: Impossible 5 Trailer Ufficiale Italiano (2015) - Tom Cruise Movie HD\" width=\"860\" height=\"484\" src=\"https:\/\/www.youtube.com\/embed\/j4Bp2nQw_6U?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>9 &#8211; <strong>Austin Powers<\/strong><\/p>\n<p>L&#8217;agente segreto britannico ibernato negli anni &#8217;60 e scongelato alla fine dei &#8217;90, creato da\u00a0<strong>Mike Myers<\/strong> \u00e8 probabilmente la creazione comica pi\u00f9 riuscita degli ultimi 25 anni insieme a\u00a0<strong>Mr. Bean<\/strong> e\u00a0<strong>Ace Ventura<\/strong>. Protagonista di tre film (<em>Austin Powers &#8211; Il controspione<\/em>,\u00a0<em>Austin Powers &#8211; La spia che ci provava<\/em> e\u00a0<em>Austin Powers in Goldmember<\/em>), la spia nostalgica della\u00a0<em>swinging london<\/em> e della libert\u00e0 sessuale (il\u00a0<em>mojo<\/em> dell&#8217;originale diventa il discutibile &#8220;maipi\u00f9moscio&#8221; della traduzione italiana) \u00e8 diventata personaggio di culto, come il suo antagonista\u00a0<strong>Dottor Male<\/strong>\u00a0ed il suo clone in miniatura\u00a0<strong>Mini me<\/strong>. Non molti hanno resistito all&#8217;idea di apparire in autoironici cameo: da\u00a0<strong>Burt Bacharach<\/strong> a\u00a0<strong>Elvis Costello<\/strong> passando per\u00a0<strong>Tom Cruise<\/strong>,<strong>\u00a0Britney Spears<\/strong>,\u00a0<strong>Gwyneth Paltrow<\/strong>, <strong>Kevin Spacey<\/strong>,\u00a0<strong>Danny DeVito<\/strong>\u00a0<strong>Ozzy Osbourne<\/strong> e addirittura\u00a0<strong>Steven Spielberg<\/strong>.<\/p>\n<p><iframe loading=\"lazy\" title=\"Tom Cruise is Austin Powers in Goldmemeber HD\" width=\"860\" height=\"484\" src=\"https:\/\/www.youtube.com\/embed\/vFhrc32kF6E?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>10 &#8211; <strong>Dr. Neil Connery<\/strong><\/p>\n<p>Il genio del bis italico. Tra le tante spie di imitazione (077, 008, 070) di cui conservano traccia alcune pubblicazioni quali\u00a0<em>Mondi incredibili<\/em> di\u00a0<strong>Antonio Bruschini<\/strong> e\u00a0<strong>Antonio Tentori<\/strong> ed il pi\u00f9 recente\u00a0<em>007 all&#8217;italiana<\/em> di\u00a0<strong>Marco Giusti<\/strong>, la palma per l&#8217;invenzione pi\u00f9 assurda e geniale spetta ad\u00a0<strong>Alberto De Martino\u00a0<\/strong>(responsabile anche di un\u00a0<em>Missione speciale Lady Chaplin<\/em> con la\u00a0<em>bond girl<\/em>\u00a0<strong>Daniela Bianchi<\/strong>) che nel 1967 gira\u00a0<em>Ok Connery<\/em>. S\u00ec proprio\u00a0<strong>Connery<\/strong>,\u00a0<strong>Neil Connery<\/strong>, si chiama il personaggio principale del film, ma anche l&#8217;attore che lo interpreta, fratello di\u00a0<strong>Sean<\/strong>. Gli altri attori provengono tutti dalla saga di\u00a0<strong>James Bond<\/strong>, da\u00a0<strong>Adolfo Celi<\/strong> (<strong>Emilio Largo<\/strong> in\u00a0<em>Thunderball<\/em>) a\u00a0<strong>Anthony Dawson<\/strong> (<strong>Dent<\/strong> in\u00a0<em>Licenza di uccidere<\/em> e\u00a0<strong>Blofeld<em>\u00a0<\/em><\/strong>in\u00a0<em>Dalla Russia con amore<\/em> e\u00a0<em>Thunderball<\/em>), passando per\u00a0<strong>Daniela Bianchi<\/strong> (<strong>Tatiana Romanova\u00a0<\/strong>in\u00a0<em>Dalla Russia con amore<\/em>) e, soprattutto, per\u00a0<strong>Bernard Lee<\/strong> e\u00a0<strong>Lois Maxwell<\/strong> (<strong>M\u00a0<\/strong>e\u00a0<strong>Moneypenny<\/strong> in pi\u00f9 di dieci pellicole della serie). Il tutto commentato da una colonna sonora\u00a0<em>bondeggiante<\/em> di\u00a0<strong>Morricone<\/strong> e\u00a0<strong>Nicolai<\/strong>.<\/p>\n<p><iframe loading=\"lazy\" title=\"Ok Connery \/ Operation Kid Brother \/ Operacion Hermano Peque\u00f1o (1967) - Trailer\" width=\"860\" height=\"645\" src=\"https:\/\/www.youtube.com\/embed\/Hk1gNgjrfPg?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quanti epigoni, quante parodie, quanta produzione\u00a0bis ha generato il personaggio creato da\u00a0Ian Fleming? In occasione dell&#8217;uscita del\u00a0Bond\u00a0movie n. 24,\u00a0Spectre (ma sta per arrivare anche\u00a0Il ponte delle spie di\u00a0Spielberg), questa playlist \u00e8 dedicata a loro.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[950,919],"tags":[1415,1412,1417,1422,1420,1411,1416,1413,1418,1419,1421,1414,1423,1410],"class_list":["post-1516","post","type-post","status-publish","format-standard","hentry","category-analisi-e-critica-2","category-playlist","tag-austin-powers","tag-ethan-hunt","tag-franco-e-ciccio","tag-george-smiley","tag-harry-palmer","tag-james-bond","tag-james-tont","tag-jason-bourne","tag-lando-buzzanca","tag-mata-hari","tag-matt-helm","tag-neil-connery","tag-oss-117","tag-spy-movie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gli altri Bond - 10 cinespie alternative a 007<\/title>\n<meta name=\"description\" content=\"Epigoni e parodie dell&#039;agente segreto pi\u00f9 famoso del mondo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pigrecoemme.com\/blog\/gli-altri-bond-10-cinespie-alternative-a-007\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gli altri Bond - 10 cinespie alternative a 007\" \/>\n<meta property=\"og:description\" content=\"Epigoni e parodie dell&#039;agente segreto pi\u00f9 famoso del mondo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pigrecoemme.com\/blog\/gli-altri-bond-10-cinespie-alternative-a-007\/\" \/>\n<meta property=\"og:site_name\" content=\"Scuola di Cinema Pigrecoemme - Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pigrecoemme\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/rosario.gallone\" \/>\n<meta property=\"article:published_time\" content=\"2015-11-04T22:56:09+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2015\/10\/bond.jpg\" \/>\n<meta name=\"author\" content=\"Rosario Gallone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RosarioGallone\" \/>\n<meta name=\"twitter:site\" content=\"@Pigrecoemme\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rosario Gallone\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/gli-altri-bond-10-cinespie-alternative-a-007\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/gli-altri-bond-10-cinespie-alternative-a-007\\\/\"},\"author\":{\"name\":\"Rosario Gallone\",\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/#\\\/schema\\\/person\\\/3fdd423e7c221a503812a1e86daec850\"},\"headline\":\"Gli altri Bond &#8211; 10 cinespie alternative a 007\",\"datePublished\":\"2015-11-04T22:56:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/gli-altri-bond-10-cinespie-alternative-a-007\\\/\"},\"wordCount\":1635,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/gli-altri-bond-10-cinespie-alternative-a-007\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/bond.jpg\",\"keywords\":[\"austin powers\",\"ethan hunt\",\"franco e ciccio\",\"george smiley\",\"harry palmer\",\"james bond\",\"james tont\",\"jason bourne\",\"lando buzzanca\",\"mata hari\",\"matt helm\",\"neil connery\",\"oss 117\",\"spy movie\"],\"articleSection\":[\"Analisi e Critica\",\"Playlist\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/gli-altri-bond-10-cinespie-alternative-a-007\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/gli-altri-bond-10-cinespie-alternative-a-007\\\/\",\"url\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/gli-altri-bond-10-cinespie-alternative-a-007\\\/\",\"name\":\"Gli altri Bond - 10 cinespie alternative a 007\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/gli-altri-bond-10-cinespie-alternative-a-007\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/gli-altri-bond-10-cinespie-alternative-a-007\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/bond.jpg\",\"datePublished\":\"2015-11-04T22:56:09+00:00\",\"description\":\"Epigoni e parodie dell'agente segreto pi\u00f9 famoso del mondo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/gli-altri-bond-10-cinespie-alternative-a-007\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/gli-altri-bond-10-cinespie-alternative-a-007\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/gli-altri-bond-10-cinespie-alternative-a-007\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/bond.jpg\",\"contentUrl\":\"http:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/bond.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/gli-altri-bond-10-cinespie-alternative-a-007\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gli altri Bond &#8211; 10 cinespie alternative a 007\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/\",\"name\":\"Scuola di Cinema Pigrecoemme - Blog\",\"description\":\"Siamo la prima Scuola di Cinema e Fotografia di Napoli\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/#organization\",\"name\":\"Scuola di cinema e fotografia Pigrecoemme\",\"url\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.pigrecoemme.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/logo-pigrecoemme-2018.png?fit=500%2C500&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.pigrecoemme.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/logo-pigrecoemme-2018.png?fit=500%2C500&ssl=1\",\"width\":500,\"height\":500,\"caption\":\"Scuola di cinema e fotografia Pigrecoemme\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pigrecoemme\",\"https:\\\/\\\/x.com\\\/Pigrecoemme\",\"https:\\\/\\\/www.instagram.com\\\/pigrecoemme\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/pigrecoemme\\\/\",\"https:\\\/\\\/www.youtube.com\\\/pigrecoemme\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/#\\\/schema\\\/person\\\/3fdd423e7c221a503812a1e86daec850\",\"name\":\"Rosario Gallone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7172808a86a713dea422a3159a5fe73d8a0718671410a281103d82dea575d3e9?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7172808a86a713dea422a3159a5fe73d8a0718671410a281103d82dea575d3e9?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7172808a86a713dea422a3159a5fe73d8a0718671410a281103d82dea575d3e9?s=96&r=g\",\"caption\":\"Rosario Gallone\"},\"description\":\"Rosario \u00e8 tra i fondatori della Pigrecoemme, dove si occupa soprattutto del corso di regia e dell'organizzazione dei corsi. E' autore della sceneggiatura di Isa 9000 (mediometraggio con Isa Danieli diretto da Angelo Serio), del montaggio di documentari e della regia di alcuni cortometraggi.\",\"sameAs\":[\"http:\\\/\\\/www.pigrecoemme.com\\\/\",\"https:\\\/\\\/www.facebook.com\\\/rosario.gallone\",\"https:\\\/\\\/x.com\\\/RosarioGallone\"],\"url\":\"https:\\\/\\\/www.pigrecoemme.com\\\/blog\\\/author\\\/rosario-gallone\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gli altri Bond - 10 cinespie alternative a 007","description":"Epigoni e parodie dell'agente segreto pi\u00f9 famoso del mondo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pigrecoemme.com\/blog\/gli-altri-bond-10-cinespie-alternative-a-007\/","og_locale":"it_IT","og_type":"article","og_title":"Gli altri Bond - 10 cinespie alternative a 007","og_description":"Epigoni e parodie dell'agente segreto pi\u00f9 famoso del mondo.","og_url":"https:\/\/www.pigrecoemme.com\/blog\/gli-altri-bond-10-cinespie-alternative-a-007\/","og_site_name":"Scuola di Cinema Pigrecoemme - Blog","article_publisher":"https:\/\/www.facebook.com\/pigrecoemme","article_author":"https:\/\/www.facebook.com\/rosario.gallone","article_published_time":"2015-11-04T22:56:09+00:00","og_image":[{"url":"http:\/\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2015\/10\/bond.jpg","type":"","width":"","height":""}],"author":"Rosario Gallone","twitter_card":"summary_large_image","twitter_creator":"@RosarioGallone","twitter_site":"@Pigrecoemme","twitter_misc":{"Scritto da":"Rosario Gallone","Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.pigrecoemme.com\/blog\/gli-altri-bond-10-cinespie-alternative-a-007\/#article","isPartOf":{"@id":"https:\/\/www.pigrecoemme.com\/blog\/gli-altri-bond-10-cinespie-alternative-a-007\/"},"author":{"name":"Rosario Gallone","@id":"https:\/\/www.pigrecoemme.com\/blog\/#\/schema\/person\/3fdd423e7c221a503812a1e86daec850"},"headline":"Gli altri Bond &#8211; 10 cinespie alternative a 007","datePublished":"2015-11-04T22:56:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.pigrecoemme.com\/blog\/gli-altri-bond-10-cinespie-alternative-a-007\/"},"wordCount":1635,"commentCount":0,"publisher":{"@id":"https:\/\/www.pigrecoemme.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.pigrecoemme.com\/blog\/gli-altri-bond-10-cinespie-alternative-a-007\/#primaryimage"},"thumbnailUrl":"http:\/\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2015\/10\/bond.jpg","keywords":["austin powers","ethan hunt","franco e ciccio","george smiley","harry palmer","james bond","james tont","jason bourne","lando buzzanca","mata hari","matt helm","neil connery","oss 117","spy movie"],"articleSection":["Analisi e Critica","Playlist"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.pigrecoemme.com\/blog\/gli-altri-bond-10-cinespie-alternative-a-007\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.pigrecoemme.com\/blog\/gli-altri-bond-10-cinespie-alternative-a-007\/","url":"https:\/\/www.pigrecoemme.com\/blog\/gli-altri-bond-10-cinespie-alternative-a-007\/","name":"Gli altri Bond - 10 cinespie alternative a 007","isPartOf":{"@id":"https:\/\/www.pigrecoemme.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pigrecoemme.com\/blog\/gli-altri-bond-10-cinespie-alternative-a-007\/#primaryimage"},"image":{"@id":"https:\/\/www.pigrecoemme.com\/blog\/gli-altri-bond-10-cinespie-alternative-a-007\/#primaryimage"},"thumbnailUrl":"http:\/\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2015\/10\/bond.jpg","datePublished":"2015-11-04T22:56:09+00:00","description":"Epigoni e parodie dell'agente segreto pi\u00f9 famoso del mondo.","breadcrumb":{"@id":"https:\/\/www.pigrecoemme.com\/blog\/gli-altri-bond-10-cinespie-alternative-a-007\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pigrecoemme.com\/blog\/gli-altri-bond-10-cinespie-alternative-a-007\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.pigrecoemme.com\/blog\/gli-altri-bond-10-cinespie-alternative-a-007\/#primaryimage","url":"http:\/\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2015\/10\/bond.jpg","contentUrl":"http:\/\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2015\/10\/bond.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.pigrecoemme.com\/blog\/gli-altri-bond-10-cinespie-alternative-a-007\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.pigrecoemme.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Gli altri Bond &#8211; 10 cinespie alternative a 007"}]},{"@type":"WebSite","@id":"https:\/\/www.pigrecoemme.com\/blog\/#website","url":"https:\/\/www.pigrecoemme.com\/blog\/","name":"Scuola di Cinema Pigrecoemme - Blog","description":"Siamo la prima Scuola di Cinema e Fotografia di Napoli","publisher":{"@id":"https:\/\/www.pigrecoemme.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pigrecoemme.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.pigrecoemme.com\/blog\/#organization","name":"Scuola di cinema e fotografia Pigrecoemme","url":"https:\/\/www.pigrecoemme.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.pigrecoemme.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2018\/06\/logo-pigrecoemme-2018.png?fit=500%2C500&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2018\/06\/logo-pigrecoemme-2018.png?fit=500%2C500&ssl=1","width":500,"height":500,"caption":"Scuola di cinema e fotografia Pigrecoemme"},"image":{"@id":"https:\/\/www.pigrecoemme.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pigrecoemme","https:\/\/x.com\/Pigrecoemme","https:\/\/www.instagram.com\/pigrecoemme\/","https:\/\/www.linkedin.com\/company\/pigrecoemme\/","https:\/\/www.youtube.com\/pigrecoemme"]},{"@type":"Person","@id":"https:\/\/www.pigrecoemme.com\/blog\/#\/schema\/person\/3fdd423e7c221a503812a1e86daec850","name":"Rosario Gallone","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/7172808a86a713dea422a3159a5fe73d8a0718671410a281103d82dea575d3e9?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7172808a86a713dea422a3159a5fe73d8a0718671410a281103d82dea575d3e9?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7172808a86a713dea422a3159a5fe73d8a0718671410a281103d82dea575d3e9?s=96&r=g","caption":"Rosario Gallone"},"description":"Rosario \u00e8 tra i fondatori della Pigrecoemme, dove si occupa soprattutto del corso di regia e dell'organizzazione dei corsi. E' autore della sceneggiatura di Isa 9000 (mediometraggio con Isa Danieli diretto da Angelo Serio), del montaggio di documentari e della regia di alcuni cortometraggi.","sameAs":["http:\/\/www.pigrecoemme.com\/","https:\/\/www.facebook.com\/rosario.gallone","https:\/\/x.com\/RosarioGallone"],"url":"https:\/\/www.pigrecoemme.com\/blog\/author\/rosario-gallone\/"}]}},"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":1419,"url":"https:\/\/www.pigrecoemme.com\/blog\/cercasi-10-vecchi-film-misteriosamente-scomparsi\/","url_meta":{"origin":1516,"position":0},"title":"Cercasi 10 vecchi film misteriosamente scomparsi","author":"Rosario Gallone","date":"16 Luglio 2015","format":false,"excerpt":"\u00a0 Questa non \u00e8 una playlist.\u00a0\u00c8 una lista dei desideri. I tempi delle ricerche faticose, ma gratificanti, tra i palinsesti notturni, i cestoni di VHS dei mercati, gli annunci sulle riviste, sembravano essere finiti. Il moltiplicarsi di canali e, tra questi, di quelli tematici, delle chicche in DVD e, soprattutto,\u2026","rel":"","context":"In &quot;Analisi e Critica&quot;","block_context":{"text":"Analisi e Critica","link":"https:\/\/www.pigrecoemme.com\/blog\/analisi-e-critica-2\/"},"img":{"alt_text":"film introvabili","src":"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2015\/07\/film-introvabili2.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2820,"url":"https:\/\/www.pigrecoemme.com\/blog\/l-heist-movie-allitaliana-in-10-film\/","url_meta":{"origin":1516,"position":1},"title":"L&#8217;Heist Movie all&#8217;italiana in 10 film","author":"Rosario Gallone","date":"19 Luglio 2020","format":false,"excerpt":"L'heist movie (noto anche come\u00a0caper movie con un'origine da un etimo latino che lascia piuttosto perplessi) \u00e8 un sottofilone del thriller incentrato sul \"colpo grosso\". Ovviamente i titoli pi\u00f9 importanti arrivano da oltreoceano: Ocean's Eleven, Il genio della rapina, La pietra che scotta\u00a0e pi\u00f9 di recente\u00a0Inside Man.\u00a0Tuttavia negli anni '50\u2026","rel":"","context":"In &quot;Analisi e Critica&quot;","block_context":{"text":"Analisi e Critica","link":"https:\/\/www.pigrecoemme.com\/blog\/analisi-e-critica-2\/"},"img":{"alt_text":"colposeggggdd6 min","src":"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2020\/07\/colposeggggdd6-min.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1721,"url":"https:\/\/www.pigrecoemme.com\/blog\/guida-al-buddy-cop-movie\/","url_meta":{"origin":1516,"position":2},"title":"Guida al Buddy Cop Movie in 10 film","author":"Rosario Gallone","date":"19 Giugno 2016","format":false,"excerpt":"A voler essere dei puristi, il buddy cop movie,\u00a0costola del\u00a0buddy movie ovvero il genere che si fonda su una coppia apparentemente mal assortita di caratteri, dovrebbe avere come protagonista una coppia di poliziotti e, per questo,\u00a0probabilmente\u00a0The Nice Guys, il film di\u00a0Shane Black che abbiamo utilizzato come copertina di questa playlist,\u2026","rel":"","context":"In &quot;Analisi e Critica&quot;","block_context":{"text":"Analisi e Critica","link":"https:\/\/www.pigrecoemme.com\/blog\/analisi-e-critica-2\/"},"img":{"alt_text":"buddy cop movie","src":"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2016\/06\/buddy-cop-movie.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":925,"url":"https:\/\/www.pigrecoemme.com\/blog\/i-10-horror-che-non-dovrebbero-mancare-nella-vostra-maratona-di-halloween\/","url_meta":{"origin":1516,"position":3},"title":"I 10 horror che non dovrebbero mancare nella vostra maratona di Halloween","author":"Rosario Gallone","date":"29 Ottobre 2014","format":false,"excerpt":"Non vorrete mica fare la maratona di Halloween propinando a voi ed ai vostri amici i soliti film? Pu\u00f2 essere un'occasione anche per un excursus storiografico meno scontato nel cinema horror ed \u00e8 quello che ci proponiamo di consigliarvi con questa lista. Per\u00f2 i primi due non possono mancare... 1-\u00a0\u00a0\u00a0\u00a0\u00a0\u2026","rel":"","context":"In &quot;Analisi e Critica&quot;","block_context":{"text":"Analisi e Critica","link":"https:\/\/www.pigrecoemme.com\/blog\/analisi-e-critica-2\/"},"img":{"alt_text":"10 film per halloween","src":"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2014\/10\/10-film-per-halloween.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2014\/10\/10-film-per-halloween.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2014\/10\/10-film-per-halloween.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2014\/10\/10-film-per-halloween.jpg?resize=700%2C400 2x, https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2014\/10\/10-film-per-halloween.jpg?resize=1050%2C600 3x"},"classes":[]},{"id":1474,"url":"https:\/\/www.pigrecoemme.com\/blog\/la-blaxploitation-in-10-film\/","url_meta":{"origin":1516,"position":4},"title":"La blaxploitation in 10 film","author":"Rosario Gallone","date":"6 Ottobre 2015","format":false,"excerpt":"La\u00a0blaxploitation\u00a0recava in s\u00e9 qualcosa di ambiguo. Sembrerebbe essere stato un movimento cinematografico di rivalsa dei neri, mentre i due termini dalla cui fusione deriva (black e exploitation) ne svelano l'intima, ed oseremmo dire atavica, natura di \"sfruttamento\" dei \"neri\". Forse fu entrambe le cose. \u00a0Nella maggior parte dei casi, infatti,\u2026","rel":"","context":"In &quot;Analisi e Critica&quot;","block_context":{"text":"Analisi e Critica","link":"https:\/\/www.pigrecoemme.com\/blog\/analisi-e-critica-2\/"},"img":{"alt_text":"badass","src":"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2015\/09\/badass.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1254,"url":"https:\/\/www.pigrecoemme.com\/blog\/10-film-che-svelano-il-gombloddoh\/","url_meta":{"origin":1516,"position":5},"title":"10 film che svelano il GOMBLODDOH!","author":"Rosario Gallone","date":"5 Marzo 2015","format":false,"excerpt":"Non vi nascondiamo che ci avevamo pensato, ma a dispetto del\u00a0titolo della playlist (e dell'immagine di \"Ti ammazzer\u00f2 Torreeeeeee!\"), abbiamo deciso di\u00a0parlarne seriamente. Perch\u00e9, piaccia o no, il complottismo o teoria del complotto o\u00a0conspiracy theory, ha radici meno fantasiose\u00a0dei rettiliani, delle scie chimiche, dei microchip sottopelle e della superbufala del\u2026","rel":"","context":"In &quot;Analisi e Critica&quot;","block_context":{"text":"Analisi e Critica","link":"https:\/\/www.pigrecoemme.com\/blog\/analisi-e-critica-2\/"},"img":{"alt_text":"gombloddohr","src":"https:\/\/i0.wp.com\/www.pigrecoemme.com\/blog\/wp-content\/uploads\/2015\/03\/gombloddohr.png?resize=350%2C200","width":350,"height":200},"classes":[]}],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.pigrecoemme.com\/blog\/wp-json\/wp\/v2\/posts\/1516","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pigrecoemme.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pigrecoemme.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pigrecoemme.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pigrecoemme.com\/blog\/wp-json\/wp\/v2\/comments?post=1516"}],"version-history":[{"count":0,"href":"https:\/\/www.pigrecoemme.com\/blog\/wp-json\/wp\/v2\/posts\/1516\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.pigrecoemme.com\/blog\/wp-json\/wp\/v2\/media?parent=1516"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pigrecoemme.com\/blog\/wp-json\/wp\/v2\/categories?post=1516"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pigrecoemme.com\/blog\/wp-json\/wp\/v2\/tags?post=1516"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}